{"id":7876,"date":"2025-07-08T09:47:24","date_gmt":"2025-07-08T07:47:24","guid":{"rendered":"https:\/\/vbw.entwicklung-mediengewerk.de\/?post_type=termin&#038;p=7876"},"modified":"2025-07-08T09:47:24","modified_gmt":"2025-07-08T07:47:24","slug":"freitag-concierge-rehwald","status":"publish","type":"termin","link":"https:\/\/www.klarenthal-vbw.de\/ar\/termin\/freitag-concierge-rehwald\/","title":{"rendered":"Freitag"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":true},"categories":[],"tags":[81],"ort":[],"teamtag":[141],"class_list":["post-7876","termin","type-termin","status-publish","hentry","tag-concierge","teamtag-iris-rehwald"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Freitag - Volksbildungswerk Klarenthal e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.klarenthal-vbw.de\/ar\/termin\/freitag-concierge-rehwald\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Freitag - Volksbildungswerk Klarenthal e.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.klarenthal-vbw.de\/ar\/termin\/freitag-concierge-rehwald\/\" \/>\n<meta property=\"og:site_name\" content=\"Volksbildungswerk Klarenthal e.V.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/ar\\\/termin\\\/freitag-concierge-rehwald\\\/\",\"url\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/ar\\\/termin\\\/freitag-concierge-rehwald\\\/\",\"name\":\"Freitag - Volksbildungswerk Klarenthal e.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/ar\\\/#website\"},\"datePublished\":\"2025-07-08T07:47:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/ar\\\/termin\\\/freitag-concierge-rehwald\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.klarenthal-vbw.de\\\/ar\\\/termin\\\/freitag-concierge-rehwald\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/ar\\\/termin\\\/freitag-concierge-rehwald\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Freitag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/ar\\\/\",\"name\":\"Volksbildungswerk Klarenthal e.V.\",\"description\":\"Chancen. Bildung. Perspektiven\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/ar\\\/#organization\",\"name\":\"Volksbildungswerk Klarenthal e.V.\",\"url\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo.svg\",\"caption\":\"Volksbildungswerk Klarenthal e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Freitag - Volksbildungswerk Klarenthal e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.klarenthal-vbw.de\/ar\/termin\/freitag-concierge-rehwald\/","og_locale":"ar_AR","og_type":"article","og_title":"Freitag - Volksbildungswerk Klarenthal e.V.","og_url":"https:\/\/www.klarenthal-vbw.de\/ar\/termin\/freitag-concierge-rehwald\/","og_site_name":"Volksbildungswerk Klarenthal e.V.","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.klarenthal-vbw.de\/ar\/termin\/freitag-concierge-rehwald\/","url":"https:\/\/www.klarenthal-vbw.de\/ar\/termin\/freitag-concierge-rehwald\/","name":"Freitag - Volksbildungswerk Klarenthal e.V.","isPartOf":{"@id":"https:\/\/www.klarenthal-vbw.de\/ar\/#website"},"datePublished":"2025-07-08T07:47:24+00:00","breadcrumb":{"@id":"https:\/\/www.klarenthal-vbw.de\/ar\/termin\/freitag-concierge-rehwald\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.klarenthal-vbw.de\/ar\/termin\/freitag-concierge-rehwald\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.klarenthal-vbw.de\/ar\/termin\/freitag-concierge-rehwald\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.klarenthal-vbw.de\/ar\/"},{"@type":"ListItem","position":2,"name":"Freitag"}]},{"@type":"WebSite","@id":"https:\/\/www.klarenthal-vbw.de\/ar\/#website","url":"https:\/\/www.klarenthal-vbw.de\/ar\/","name":"Volksbildungswerk Klarenthal e.V.","description":"Chancen. Bildung. Perspektiven","publisher":{"@id":"https:\/\/www.klarenthal-vbw.de\/ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.klarenthal-vbw.de\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/www.klarenthal-vbw.de\/ar\/#organization","name":"Volksbildungswerk Klarenthal e.V.","url":"https:\/\/www.klarenthal-vbw.de\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.klarenthal-vbw.de\/ar\/#\/schema\/logo\/image\/","url":"https:\/\/www.klarenthal-vbw.de\/wp-content\/uploads\/2025\/02\/logo.svg","contentUrl":"https:\/\/www.klarenthal-vbw.de\/wp-content\/uploads\/2025\/02\/logo.svg","caption":"Volksbildungswerk Klarenthal e.V."},"image":{"@id":"https:\/\/www.klarenthal-vbw.de\/ar\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.klarenthal-vbw.de\/ar\/wp-json\/wp\/v2\/termin\/7876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.klarenthal-vbw.de\/ar\/wp-json\/wp\/v2\/termin"}],"about":[{"href":"https:\/\/www.klarenthal-vbw.de\/ar\/wp-json\/wp\/v2\/types\/termin"}],"wp:attachment":[{"href":"https:\/\/www.klarenthal-vbw.de\/ar\/wp-json\/wp\/v2\/media?parent=7876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.klarenthal-vbw.de\/ar\/wp-json\/wp\/v2\/categories?post=7876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.klarenthal-vbw.de\/ar\/wp-json\/wp\/v2\/tags?post=7876"},{"taxonomy":"ort","embeddable":true,"href":"https:\/\/www.klarenthal-vbw.de\/ar\/wp-json\/wp\/v2\/ort?post=7876"},{"taxonomy":"teamtag","embeddable":true,"href":"https:\/\/www.klarenthal-vbw.de\/ar\/wp-json\/wp\/v2\/teamtag?post=7876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}