{"id":8224,"date":"2025-02-27T22:07:02","date_gmt":"2025-02-27T21:07:02","guid":{"rendered":"https:\/\/vbw.entwicklung-mediengewerk.de\/soziale-stadtteilarbeit\/kultur-fuer-aeltere\/"},"modified":"2025-07-30T17:51:06","modified_gmt":"2025-07-30T15:51:06","slug":"kultur-fuer-aeltere","status":"publish","type":"page","link":"https:\/\/www.klarenthal-vbw.de\/de_LS\/soziale-stadtteilarbeit\/kultur-fuer-aeltere\/","title":{"rendered":"Kultur f\u00fcr \u00c4ltere"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8224\" class=\"elementor elementor-8224 elementor-3665\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6452e840 e-flex e-con-boxed e-con e-parent\" data-id=\"6452e840\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b622c7 animated-slow elementor-widget__width-initial elementor-view-default elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"3b622c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" viewBox=\"0 0 48.064 48.064\"><g><path d=\"M13,26.93h-2c-.028,0-.05-.022-.05-.05s.022-.05.05-.05h2c.027,0,.05.022.05.05s-.022.05-.05.05Z\"><\/path><path d=\"M13,28.93h-2c-.028,0-.05-.022-.05-.05s.022-.05.05-.05h2c.027,0,.05.022.05.05s-.022.05-.05.05Z\"><\/path><path d=\"M10,32.18c-.166,0-.3-.135-.3-.3s.134-.3.3-.3v.1c-.11,0-.2.09-.2.2s.09.2.2.2v.1Z\"><\/path><path d=\"M10,32.18v-.1c.11,0,.2-.09.2-.2s-.09-.2-.2-.2v-.1c.166,0,.3.135.3.3s-.134.3-.3.3Z\"><\/path><path d=\"M14,32.18c-.165,0-.3-.135-.3-.3s.135-.3.3-.3v.1c-.11,0-.2.09-.2.2s.09.2.2.2v.1Z\"><\/path><path d=\"M14,32.18v-.1c.11,0,.2-.09.2-.2s-.09-.2-.2-.2v-.1c.165,0,.3.135.3.3s-.135.3-.3.3Z\"><\/path><path d=\"M11.997,40.282c-.581,0-1.167-.129-1.697-.372l-2.31-1.068c-.75-.347-1.368-.905-1.788-1.617-.42-.712-.611-1.524-.551-2.349l.3-3.001c.002-.021.017-.038.036-.043.023-.008.042,0,.054.018l2.135,2.847c.248.331.586.571.979.693.392.124.807.12,1.199-.011,1.062-.354,2.232-.354,3.295,0,.391.131.804.137,1.199.011.393-.122.73-.362.979-.693l2.135-2.847c.013-.017.033-.026.054-.018.02.005.034.022.036.043l.3,3c.059.826-.133,1.639-.553,2.35-.419.711-1.038,1.271-1.79,1.617l-2.313,1.067c-.528.244-1.115.373-1.696.373ZM6.037,32.013l-.287,2.872c-.058.803.128,1.595.538,2.289s1.013,1.239,1.744,1.578l2.31,1.067c.517.237,1.089.363,1.655.363s1.139-.126,1.655-.363l2.313-1.067c.732-.339,1.336-.885,1.745-1.578.41-.693.596-1.485.539-2.29l-.287-2.871-2.058,2.744c-.261.348-.616.6-1.029.729-.412.131-.85.126-1.26-.011-1.043-.348-2.19-.348-3.232,0-.411.138-.847.14-1.261.011-.413-.129-.768-.381-1.028-.729l-2.058-2.744Z\"><\/path><path d=\"M12,37.513c-.375,0-.731-.118-1.03-.343-.022-.017-.026-.048-.01-.07.016-.021.047-.027.07-.01.281.211.616.323.97.323.348,0,.693-.115.97-.323.023-.018.055-.012.07.01.017.022.012.054-.01.07-.295.221-.661.343-1.03.343Z\"><\/path><path d=\"M6,31.93c-.028,0-.05-.022-.05-.05v-2c0-.518.065-1.033.195-1.532.006-.024.024-.04.055-.037.102.013.203.02.3.02.654,0,1.27-.255,1.732-.718s.718-1.078.718-1.732c0-.027.022-.05.05-.05s.05.022.05.05c0,.681-.265,1.321-.747,1.803-.481.482-1.122.747-1.803.747-.087,0-.178-.005-.269-.015-.121.478-.182.971-.182,1.465v2c0,.027-.022.05-.05.05Z\"><\/path><path d=\"M5.7,34.908h-.007c-.485-.074-.928-.319-1.247-.691s-.495-.847-.495-1.337c0-.1.007-.199.021-.296-.678-.322-1.246-.863-1.601-1.526-.361-.673-.497-1.46-.381-2.216.115-.755.48-1.465,1.026-2,.538-.525,1.242-.872,1.987-.978.09-.435.292-.84.587-1.173.302-.342.692-.597,1.127-.737.435-.141.9-.16,1.345-.06.435.099.835.309,1.162.609.855-.44,1.813-.673,2.775-.673s1.92.232,2.774.673c.326-.301.728-.511,1.163-.609.443-.101.908-.081,1.345.06.436.141.825.396,1.127.737.295.332.497.737.588,1.173.744.105,1.448.452,1.987.978.546.534.91,1.244,1.026,2,.115.758-.021,1.545-.382,2.216-.355.663-.923,1.204-1.601,1.526.015.096.021.195.021.296,0,.491-.176.966-.495,1.337-.319.372-.763.617-1.247.691-.025,0-.054-.015-.058-.042s.015-.053.042-.058c.462-.07.883-.304,1.187-.656.304-.354.472-.806.472-1.272,0-.107-.009-.215-.026-.316-.004-.022.007-.045.028-.054.673-.312,1.237-.844,1.589-1.499.351-.653.482-1.418.37-2.153-.112-.734-.467-1.425-.997-1.943-.531-.52-1.229-.858-1.966-.955-.021-.003-.038-.02-.042-.04-.084-.432-.281-.833-.571-1.161s-.665-.573-1.084-.708c-.418-.136-.865-.156-1.292-.058-.429.097-.824.308-1.142.608-.015.014-.038.018-.058.008-.848-.443-1.803-.678-2.76-.678s-1.912.234-2.76.678c-.02.01-.042.006-.057-.008-.318-.301-.713-.512-1.142-.608-.427-.099-.873-.078-1.292.058-.418.135-.792.38-1.083.708-.292.328-.489.729-.571,1.161-.004.021-.021.037-.043.04-.736.097-1.435.436-1.965.955-.531.52-.886,1.21-.998,1.943-.112.734.019,1.499.37,2.153.352.654.916,1.187,1.589,1.499.021.009.032.031.028.053-.018.104-.026.21-.026.317,0,.467.167.918.472,1.272.304.353.725.586,1.186.656.027.005.046.03.042.058-.004.024-.025.042-.049.042Z\"><\/path><path d=\"M18,31.93c-.027,0-.05-.022-.05-.05v-2c0-.493-.062-.986-.183-1.465-.091.01-.179.015-.268.015-.681,0-1.321-.265-1.803-.747-.482-.481-.747-1.122-.747-1.803,0-.027.022-.05.05-.05s.05.022.05.05c0,.654.255,1.27.718,1.732s1.078.718,1.732.718c.099,0,.196-.007.3-.02.021-.004.048.013.055.037.13.501.195,1.016.195,1.532v2c0,.027-.022.05-.05.05Z\"><\/path><path d=\"M23,46.93c-.027,0-.05-.022-.05-.05v-3.105c.002-.296-.065-.593-.195-.859-.131-.267-.323-.503-.556-.681-2.28-1.594-4.955-2.522-7.733-2.686-.027-.002-.049-.025-.047-.053,0-.027.027-.047.053-.047,2.797.164,5.489,1.099,7.786,2.704.247.188.449.437.587.719.137.279.207.592.205.902v3.105c0,.027-.022.05-.05.05Z\"><\/path><path d=\"M1,46.93c-.028,0-.05-.022-.05-.05v-3.105c-.001-.31.07-.621.206-.899.136-.279.338-.526.583-.716,2.298-1.607,4.991-2.544,7.789-2.71.023,0,.051.02.053.047.002.027-.019.051-.047.053-2.779.165-5.454,1.096-7.735,2.691-.231.179-.423.413-.553.678-.13.266-.198.562-.196.856v3.105c0,.027-.022.05-.05.05Z\"><\/path><path d=\"M7.517,43.568h-.011c-.152-.002-.299-.047-.424-.129-.125-.081-.226-.197-.289-.336-.062-.137-.084-.289-.064-.438l.368-2.792c.003-.026.029-.046.056-.043.027.004.047.029.043.057l-.368,2.792c-.018.131.001.264.056.384.056.121.143.223.252.293.11.072.238.111.371.113h.01c.129,0,.255-.035.364-.104,1.134-.665,2.369-1.075,3.671-1.219-.569-.086-1.106-.333-1.545-.715-.552-.482-.912-1.147-1.013-1.873-.004-.027.015-.053.042-.057.025-.003.052.015.056.043.098.702.446,1.345.98,1.811.535.467,1.219.724,1.928.725.026,0,.048.02.05.046s-.016.049-.042.054l-.384.06c-1.312.137-2.554.545-3.691,1.212-.124.077-.268.117-.416.117Z\"><\/path><path d=\"M16.482,43.568c-.147,0-.291-.04-.416-.117-1.137-.667-2.377-1.075-3.688-1.212l-.386-.06c-.026-.005-.044-.027-.042-.054s.023-.046.05-.046c.708,0,1.393-.258,1.927-.725.534-.465.883-1.107.98-1.811.004-.025.025-.043.05-.043h.007c.027.004.047.029.043.057-.102.727-.462,1.392-1.014,1.873-.439.382-.976.629-1.545.715,1.301.144,2.537.554,3.67,1.219.11.067.235.104.364.104h.01c.134-.002.262-.041.371-.113.111-.071.198-.173.253-.293s.074-.253.056-.384l-.368-2.792c-.003-.027.016-.053.043-.057h.007c.024,0,.046.019.05.043l.368,2.792c.021.149,0,.301-.063.438-.063.138-.163.254-.29.336-.125.082-.271.127-.424.129h-.012Z\"><\/path><path d=\"M12,46.93c-.028,0-.05-.022-.05-.05v-4.75c0-.027.022-.05.05-.05s.05.022.05.05v4.75c0,.027-.022.05-.05.05Z\"><\/path><path d=\"M16,46.93c-.027,0-.05-.022-.05-.05v-1.5c0-.027.022-.05.05-.05s.05.022.05.05v1.5c0,.027-.022.05-.05.05Z\"><\/path><path d=\"M19,46.93c-.027,0-.05-.022-.05-.05v-6.391c0-.027.022-.05.05-.05s.05.022.05.05v6.391c0,.027-.022.05-.05.05Z\"><\/path><path d=\"M8,46.93c-.028,0-.05-.022-.05-.05v-1.5c0-.027.022-.05.05-.05s.05.022.05.05v1.5c0,.027-.022.05-.05.05Z\"><\/path><path d=\"M5,46.93c-.028,0-.05-.022-.05-.05v-6.391c0-.027.022-.05.05-.05s.05.022.05.05v6.391c0,.027-.022.05-.05.05Z\"><\/path><\/g><g><path d=\"M35.585,30.933c-3.677,0-7.354-.335-11.005-1.005-.027-.005-.045-.03-.04-.058.004-.027.031-.048.058-.04,7.291,1.337,14.685,1.337,21.976,0,.026-.009.053.013.058.04s-.013.053-.04.058c-3.651.67-7.328,1.005-11.006,1.005Z\"><\/path><path d=\"M46.582,46.931c-.027,0-.05-.022-.05-.05v-2.105c.002-.295-.065-.592-.194-.857-.13-.266-.322-.501-.556-.681-1.373-1.048-4.523-2.805-10.196-2.805s-8.819,1.757-10.197,2.805c-.234.18-.426.416-.555.681-.13.266-.197.562-.195.857v2.105c0,.027-.022.05-.05.05s-.05-.022-.05-.05v-2.105c-.002-.311.068-.622.205-.901.135-.278.337-.526.584-.717,1.388-1.055,4.566-2.824,10.258-2.824s8.874,1.77,10.257,2.824c.246.189.448.438.585.718.136.279.206.591.204.9v2.105c0,.027-.022.05-.05.05Z\"><\/path><path d=\"M35.586,35.434c-.548,0-1.091-.181-1.53-.51-.021-.017-.026-.048-.01-.07.017-.021.049-.027.07-.01.421.316.943.49,1.47.49s1.049-.174,1.47-.49c.021-.018.054-.012.07.01.017.022.012.054-.01.07-.439.329-.982.51-1.53.51Z\"><\/path><path d=\"M42.024,38.384c-.315,0-.632-.033-.947-.1-.026-.006-.044-.032-.038-.06.005-.023.025-.039.049-.039.003,0,.007,0,.011,0,.929.198,1.882.094,2.75-.297.068-.035.129-.091.173-.159.043-.069.067-.148.07-.229.002-.079-.017-.161-.055-.231s-.096-.131-.165-.173c-1.846-1.219-2.338-4.478-2.338-6.211,0-.027.022-.05.05-.05s.05.022.05.05c0,1.714.483,4.933,2.292,6.126.083.051.152.124.199.211s.069.185.066.282-.032.194-.086.278c-.053.084-.127.152-.213.196-.597.269-1.229.404-1.868.404Z\"><\/path><path d=\"M29.141,38.382c-.637,0-1.267-.135-1.859-.4-.089-.046-.163-.114-.216-.198-.054-.084-.083-.181-.086-.278-.004-.099.02-.196.067-.283.046-.086.115-.159.2-.211,1.808-1.192,2.29-4.411,2.29-6.125,0-.027.022-.05.05-.05s.05.022.05.05c0,1.733-.492,4.992-2.336,6.21-.071.043-.128.104-.166.174-.039.071-.059.151-.056.231.003.081.027.16.07.229.044.068.104.124.176.161.869.39,1.825.491,2.754.29.028-.008.054.011.06.038s-.012.054-.038.06c-.319.068-.641.103-.96.103Z\"><\/path><path d=\"M35.586,38.434c-1.616,0-3.135-.629-4.277-1.771-1.143-1.144-1.771-2.662-1.771-4.276v-2.507c0-1.614.629-3.133,1.771-4.276,1.143-1.143,2.661-1.771,4.277-1.771s3.134.629,4.276,1.771,1.771,2.661,1.771,4.276v2.507c0,1.615-.629,3.134-1.771,4.276s-2.661,1.771-4.276,1.771ZM35.586,23.931c-1.589,0-3.083.619-4.207,1.742-1.123,1.125-1.742,2.618-1.742,4.206v2.507c0,1.588.619,3.081,1.742,4.206,1.124,1.123,2.618,1.742,4.207,1.742s3.082-.619,4.206-1.742c1.123-1.124,1.742-2.617,1.742-4.206v-2.507c0-1.589-.619-3.082-1.742-4.206-1.124-1.123-2.617-1.742-4.206-1.742Z\"><\/path><path d=\"M35.585,30.928c-2.005,0-4.011-.087-6.002-.261-.026-.002-.046-.023-.046-.05v-.738c0-.771.144-1.525.43-2.241.009-.021.029-.026.051-.031,3.695.297,7.441.297,11.137,0h.004c.021,0,.039.012.047.031.285.716.43,1.471.429,2.241v.738c0,.026-.02.048-.046.05-1.991.174-3.997.261-6.003.261ZM29.637,30.571c3.946.341,7.949.342,11.897,0v-.692c0-.746-.137-1.476-.409-2.17-3.677.296-7.403.294-11.078,0-.273.693-.411,1.423-.41,2.17v.692Z\"><\/path><path d=\"M35.586,43.925c-.006,0-.012,0-.018-.003l-2.699-1.013c-.394-.146-.728-.407-.967-.752-.239-.344-.365-.747-.365-1.167v-.281c0-.027.022-.05.05-.05s.05.022.05.05v.281c0,.399.12.783.348,1.11.228.328.546.575.92.715l2.682,1.006,2.682-1.006c.374-.14.691-.387.919-.715.228-.327.348-.711.348-1.11v-.281c0-.027.022-.05.05-.05s.05.022.05.05v.281c0,.42-.126.823-.365,1.167-.239.345-.573.604-.966.752l-2.699,1.013c-.006.002-.012.003-.018.003Z\"><\/path><path d=\"M35.586,46.925c-.027,0-.05-.022-.05-.05v-3c0-.027.022-.05.05-.05s.05.022.05.05v3c0,.027-.022.05-.05.05Z\"><\/path><path d=\"M33.586,32.685c-.165,0-.3-.135-.3-.3s.135-.3.3-.3v.1c-.11,0-.2.09-.2.2s.09.2.2.2v.1Z\"><\/path><path d=\"M33.586,32.685v-.1c.11,0,.2-.09.2-.2s-.09-.2-.2-.2v-.1c.165,0,.3.135.3.3s-.135.3-.3.3Z\"><\/path><g><path d=\"M37.585,32.685c-.165,0-.3-.135-.3-.3s.135-.3.3-.3v.1c-.11,0-.2.09-.2.2s.09.2.2.2v.1Z\"><\/path><path d=\"M37.585,32.685v-.1c.11,0,.2-.09.2-.2s-.09-.2-.2-.2v-.1c.165,0,.3.135.3.3s-.135.3-.3.3Z\"><\/path><\/g><\/g><g><path d=\"M24.589,23.931c-.016,0-.031-.007-.041-.021-.006-.009-.616-.845-2.203-1.687-1.466-.778-4.088-1.721-8.257-1.793-.303-.005-.544-.246-.549-.549v-11.501c.012-.301.262-.54.56-.54.004,0,.008,0,.012,0,.241,0,.5.015.749.03.245.015.497.03.729.03.027,0,.05.022.05.05s-.022.05-.05.05c-.235,0-.489-.015-.735-.03-.248-.015-.505-.03-.744-.03h-.01c-.246,0-.451.196-.461.442v11.498c.005.247.203.445.451.45,2.314.04,5.636.387,8.31,1.809,1.604.853,2.205,1.678,2.23,1.712.016.022.011.054-.012.07-.009.006-.02.009-.029.009Z\"><\/path><path d=\"M24.589,23.931s-.01,0-.016-.002c-.021-.007-.034-.026-.034-.048v-8.5c0-.028.022-.05.05-.05s.05.022.05.05v8.357c.221-.259.862-.92,2.14-1.599,2.674-1.422,5.995-1.769,8.31-1.809.248-.005.446-.203.451-.451v-11.499c-.019-.229-.216-.41-.449-.41h-1.001c-.027,0-.05-.022-.05-.05s.022-.05.05-.05h1.001c.285,0,.526.222.549.506v11.504c-.005.304-.246.545-.549.55-4.169.072-6.791,1.015-8.257,1.793-1.587.842-2.197,1.678-2.203,1.687-.01.013-.025.021-.041.021Z\"><\/path><path d=\"M22.379,10.658c-.198,0-.41-.04-.637-.12-2.097-.603-3.586-2.474-3.703-4.655,0-2.787,2.714-5.052,6.05-5.052.031,0,.063,0,.095,0,1.645,0,3.218.606,4.438,1.714.021.019.022.05.004.071-.018.02-.052.022-.07.003-1.202-1.09-2.752-1.688-4.373-1.688-.031,0-.062,0-.093,0-3.282,0-5.951,2.221-5.951,4.95.115,2.136,1.575,3.97,3.634,4.562.9.316,1.531-.012,1.99-1.033.286-.871,1.23-1.349,2.104-1.064.297.097.56.274.76.513.018.021.016.053-.006.07-.022.018-.053.014-.07-.006-.188-.225-.436-.391-.715-.482-.823-.267-1.711.183-1.979,1.006-.365.812-.853,1.211-1.478,1.211Z\"><\/path><path d=\"M26.589,13.111c-.008,0-.016-.001-.022-.005-.024-.013-.034-.042-.022-.067l3.13-6.26c.013-.025.045-.033.067-.022.024.013.034.042.022.067l-3.13,6.26c-.009.018-.026.027-.045.027Z\"><\/path><path d=\"M30.331,7.007c-.097,0-.193-.009-.291-.026-.125-.029-.243-.072-.354-.129-.369-.187-.644-.507-.772-.9s-.097-.813.091-1.183h0c.406-.812.905-1.126,1.307-1.379.382-.241.658-.416.719-.904.014-.072.051-.135.106-.18.062-.05.136-.073.222-.065.079.009.15.048.2.11.843,1.062.933,2.552.225,3.708-.255.584-.827.949-1.451.949ZM31.324,2.338c-.046,0-.09.016-.126.045s-.062.071-.07.118c-.065.532-.374.727-.765.973-.391.247-.876.553-1.27,1.34h0c-.176.345-.206.738-.085,1.106.12.368.377.667.722.843.104.053.216.093.33.12.674.124,1.354-.233,1.633-.871.689-1.126.603-2.57-.214-3.599-.033-.042-.08-.067-.134-.073-.007,0-.015-.001-.021-.001ZM29.049,4.791h0,0Z\"><\/path><path d=\"M21.839,7.431c-.717,0-1.3-.471-1.3-1.05s.583-1.05,1.3-1.05,1.3.471,1.3,1.05-.583,1.05-1.3,1.05ZM21.839,5.431c-.662,0-1.2.426-1.2.95s.538.95,1.2.95,1.2-.426,1.2-.95-.538-.95-1.2-.95Z\"><\/path><path d=\"M24.339,4.431c-.717,0-1.3-.471-1.3-1.05s.583-1.05,1.3-1.05,1.3.471,1.3,1.05-.583,1.05-1.3,1.05ZM24.339,2.431c-.662,0-1.2.426-1.2.95s.538.95,1.2.95,1.2-.426,1.2-.95-.538-.95-1.2-.95Z\"><\/path><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec7a3d7 e-grid-align-left elementor-widget__width-initial animated-slow elementor-widget-mobile__width-inherit quicklink elementor-shape-rounded elementor-grid-0 elementor-invisible elementor-widget elementor-widget-social-icons\" data-id=\"ec7a3d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-Kultur f\u00fcr \u00c4ltere Digitallotsen Icon fett elementor-repeater-item-57f4920\" href=\"#digitallotsen\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Kultur F\u00fcr \u00c4ltere Digitallotsen Icon Fett<\/span>\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" viewBox=\"0 0 24 24\"><path d=\"M23.25,19.25c-.276,0-.5-.224-.5-.5v-2.3c0-.276.224-.5.5-.5s.5.224.5.5v2.3c0,.276-.224.5-.5.5Z\"><\/path><path d=\"M16.55,23.75c-2.371,0-4.071-1.568-4.142-1.636-.101-.094-.158-.226-.158-.364v-3.969c0-.276.224-.5.5-.5s.5.224.5.5v3.736c.433.344,1.706,1.232,3.3,1.232s2.795-.884,3.2-1.224v-3.745c0-.276.224-.5.5-.5s.5.224.5.5v3.969c0,.133-.053.26-.146.354-.067.067-1.674,1.646-4.054,1.646Z\"><\/path><path d=\"M16.55,19.95c-.068,0-.138-.015-.202-.043l-6.799-3c-.182-.079-.298-.259-.298-.457s.117-.378.298-.457l6.799-3c.13-.057.278-.057.406,0l6.7,3c.18.08.296.259.296.456s-.116.376-.296.456l-6.7,3c-.064.029-.135.044-.204.044ZM10.989,16.45l5.559,2.453,5.479-2.453-5.479-2.453-5.559,2.453Z\"><\/path><path d=\"M8.237,19.396c-.175,0-.345-.092-.437-.256-1.097-1.955-1.751-5.092-1.751-8.391C6.05,4.862,8.026.25,10.55.25s4.5,4.612,4.5,10.5c0,.276-.224.5-.5.5s-.5-.224-.5-.5c0-5.599-1.845-9.5-3.5-9.5s-3.5,3.901-3.5,9.5c0,3.136.607,6.09,1.623,7.902.135.24.049.545-.191.681-.078.043-.162.063-.244.063Z\"><\/path><path d=\"M19.906,7.25H1.594c-.276,0-.5-.224-.5-.5s.224-.5.5-.5h18.312c.276,0,.5.224.5.5s-.224.5-.5.5Z\"><\/path><path d=\"M8.55,14.25H1.25c-.276,0-.5-.224-.5-.5s.224-.5.5-.5h7.3c.276,0,.5.224.5.5s-.224.5-.5.5Z\"><\/path><path d=\"M8.801,21.058c-.032,0-.065-.003-.098-.01C3.805,20.07.25,15.739.25,10.75.25,4.96,4.96.25,10.75.25s10.5,4.71,10.5,10.5c0,.276-.224.5-.5.5s-.5-.224-.5-.5c0-5.238-4.262-9.5-9.5-9.5S1.25,5.512,1.25,10.75c0,4.515,3.217,8.433,7.648,9.317.271.054.447.317.393.588-.047.238-.256.402-.49.402Z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65f0c03 elementor-widget elementor-widget-text-editor\" data-id=\"65f0c03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<h2 class=\"wp-block-heading\">Vielf\u00e4ltige Angebote f\u00fcr \u00e4ltere Menschen<\/h2>\n\n<p>Wir schaffen Orte, die verbinden, Freude bringen und den Alltag bereichern \u2013<br>besonders f\u00fcr \u00e4ltere Menschen.<br>Deshalb bieten wir ein vielseitiges Programm.<br>Seniorinnen und Senioren k\u00f6nnen sich kreativ bet\u00e4tigen,<br>Neues entdecken und mit anderen in Kontakt kommen. <\/p>\n\n<h3 class=\"wp-block-heading\">Unsere Angebote<\/h3>\n\n<ul class=\"wp-block-list\">\n<li><strong>Kreative Workshops:<\/strong> Malen, Handarbeiten, Sprachen\u2013 in unseren Kursen k\u00f6nnen Sie Ihre kreativen Seiten entfalten.<\/li>\n\n<li><strong>Bewegung und Begegnung:<\/strong> Tanzen, Gymnastik oder gemeinsame Spazierg\u00e4nge \u2013 bleiben Sie fit und lernen Sie Gleichgesinnte kennen.<\/li>\n\n<li><strong>Caf\u00e9s und Erz\u00e4hlrunden:<\/strong> Genie\u00dfen Sie einen gem\u00fctlichen Nachmittag bei Kaffee und Kuchen und teilen Sie Geschichten aus Ihrem Leben.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\">Mitmachen leicht gemacht<\/h3>\n\n<p>Egal ob Sie regelm\u00e4\u00dfig kommen oder nur ab und zu \u2013<br>bei uns ist jede und jeder willkommen!<br>Viele unserer Angebote sind kostenlos oder kosten nur wenig.<br>So kann jeder mitmachen.<br>Haben Sie Fragen oder m\u00f6chten mehr erfahren?<br>Kommen Sie einfach vorbei, rufen Sie uns an<br>oder schauen Sie online in unseren Veranstaltungskalender.<br>Wir freuen uns, Sie kennenzulernen!    <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a575b6c elementor-widget elementor-widget-menu-anchor\" data-id=\"a575b6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"digitallotsen\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d467d28 animated-slow elementor-widget__width-inherit icon-anchor-quicklink elementor-view-default elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"d467d28\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" viewBox=\"0 0 24 24\"><path d=\"M23.25,18.8c-.027,0-.05-.022-.05-.05v-2.3c0-.027.022-.05.05-.05s.05.022.05.05v2.3c0,.027-.022.05-.05.05Z\"><\/path><path d=\"M16.55,23.3c-2.194,0-3.818-1.498-3.834-1.514-.01-.009-.016-.022-.016-.036v-3.969c0-.027.022-.05.05-.05s.05.022.05.05v3.946c.172.153,1.711,1.473,3.75,1.473s3.49-1.319,3.65-1.472v-3.947c0-.027.022-.05.05-.05s.05.022.05.05v3.969c0,.014-.005.026-.015.035-.015.016-1.54,1.515-3.735,1.515Z\"><\/path><path d=\"M16.55,19.5c-.007,0-.014,0-.021-.004l-6.799-3c-.018-.008-.03-.026-.03-.046s.012-.038.03-.046l6.799-3c.014-.006.027-.006.041,0l6.7,3c.018.009.029.026.029.046s-.012.037-.029.046l-6.7,3c-.007.003-.014.004-.021.004ZM9.874,16.45l6.676,2.945,6.578-2.945-6.578-2.945-6.676,2.945Z\"><\/path><path d=\"M8.237,18.946c-.018,0-.035-.009-.043-.025-1.061-1.891-1.693-4.945-1.693-8.171C6.5,5.208,8.316.7,10.55.7s4.05,4.508,4.05,10.05c0,.028-.022.05-.05.05s-.05-.022-.05-.05c0-5.486-1.772-9.95-3.95-9.95s-3.95,4.464-3.95,9.95c0,3.209.628,6.245,1.681,8.122.014.024.005.055-.019.068-.008.004-.016.006-.024.006Z\"><\/path><path d=\"M19.906,6.8H1.594c-.028,0-.05-.022-.05-.05s.022-.05.05-.05h18.312c.027,0,.05.022.05.05s-.022.05-.05.05Z\"><\/path><path d=\"M8.55,13.8H1.25c-.028,0-.05-.022-.05-.05s.022-.05.05-.05h7.3c.028,0,.05.022.05.05s-.022.05-.05.05Z\"><\/path><path d=\"M8.801,20.607s-.006,0-.01,0C4.103,19.671.7,15.525.7,10.75.7,5.208,5.208.7,10.75.7s10.05,4.508,10.05,10.05c0,.028-.022.05-.05.05s-.05-.022-.05-.05C20.7,5.264,16.236.8,10.75.8S.8,5.264.8,10.75c0,4.729,3.369,8.832,8.011,9.759.027.005.044.031.039.059-.004.023-.025.04-.049.04Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6de3b94 elementor-widget elementor-widget-text-editor\" data-id=\"6de3b94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"wp-block-heading\">Digitallotsen | Senioren ans Netz \u2013 Gemeinsam in die digitale Welt!<\/h2>\n<p><\/p>\n<p>Sind Sie unsicher im Umgang mit Handy, Computer oder Internet? Keine Sorge, wir sind f\u00fcr Sie da! <\/p>\n<p><\/p>\n<p><strong>\u201eSenioren ans Netz\u201c<\/strong> ist ein ehrenamtliches Projekt.<br>Es hilft \u00e4lteren Menschen, die digitale Welt kennenzulernen und sicher zu nutzen. <\/p>\n<p><\/p>\n<h3 class=\"wp-block-heading\">Unsere Digitallotsen helfen bei diversen Fragestellungen:<\/h3>\n<p><\/p>\n<ul class=\"wp-block-list\">\n<li>Wie nutze ich WhatsApp, um mit Familie und Freunden in Kontakt zu bleiben?<\/li>\n\n<li>Wie melde ich mich bei Facebook oder Instagram an?<\/li>\n\n<li>Wie funktioniert Online-Banking oder das Buchen von Terminen?<\/li>\n\n<li>Wie finde ich Informationen im Internet?<\/li>\n<\/ul>\n<p><\/p>\n<h3 class=\"wp-block-heading\">Was wir bieten:<\/h3>\n<p><\/p>\n<p>Ob Sie gerade erst mit dem Smartphone anfangen<br>oder Fragen zu Apps und Programmen haben \u2013<br>wir unterst\u00fctzen Sie pers\u00f6nlich und ganz nach Ihrem Bedarf.<\/p>\n<p><\/p>\n<ul class=\"wp-block-list\">\n<li>Wir erkl\u00e4ren alles in klarer und einfacher Sprache \u2013<br>so, dass Sie es gut verstehen k\u00f6nnen.<\/li>\n\n<li>Unser Angebot ist f\u00fcr Sie kostenlos.<br>Es ist keine Anmeldung n\u00f6tig, und Sie gehen keine Verpflichtungen ein.<\/li>\n<\/ul>\n<p><\/p>\n<p><strong>Kommen Sie vorbei!<\/strong><\/p>\n<p><\/p>\n<p>Besuchen Sie uns \u2013 wir begleiten Sie auf Ihrem Weg in die digitale Welt.<br>Gemeinsam machen wir Technik einfacher und zug\u00e4nglicher.<br>F\u00fcr mehr Lebensqualit\u00e4t und Teilhabe. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Vielf\u00e4ltige Angebote f\u00fcr \u00e4ltere Menschen Wir schaffen Orte, die verbinden, Freude bringen und den Alltag bereichern \u2013besonders f\u00fcr \u00e4ltere Menschen.Deshalb bieten wir ein vielseitiges Programm.Seniorinnen und Senioren k\u00f6nnen sich kreativ bet\u00e4tigen,Neues entdecken und mit anderen in Kontakt kommen. Unsere Angebote Kreative Workshops: Malen, Handarbeiten, Sprachen\u2013 in unseren Kursen k\u00f6nnen Sie Ihre kreativen Seiten entfalten. Bewegung [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":8196,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[217],"folder":[15],"class_list":["post-8224","page","type-page","status-publish","hentry","tag-kultur-fuer-aeltere-de_ls"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kultur f\u00fcr \u00c4ltere - Volksbildungswerk Klarenthal e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.klarenthal-vbw.de\/de_LS\/soziale-stadtteilarbeit\/kultur-fuer-aeltere\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kultur f\u00fcr \u00c4ltere - Volksbildungswerk Klarenthal e.V.\" \/>\n<meta property=\"og:description\" content=\"Vielf\u00e4ltige Angebote f\u00fcr \u00e4ltere Menschen Wir schaffen Orte, die verbinden, Freude bringen und den Alltag bereichern \u2013besonders f\u00fcr \u00e4ltere Menschen.Deshalb bieten wir ein vielseitiges Programm.Seniorinnen und Senioren k\u00f6nnen sich kreativ bet\u00e4tigen,Neues entdecken und mit anderen in Kontakt kommen. Unsere Angebote Kreative Workshops: Malen, Handarbeiten, Sprachen\u2013 in unseren Kursen k\u00f6nnen Sie Ihre kreativen Seiten entfalten. Bewegung [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.klarenthal-vbw.de\/de_LS\/soziale-stadtteilarbeit\/kultur-fuer-aeltere\/\" \/>\n<meta property=\"og:site_name\" content=\"Volksbildungswerk Klarenthal e.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-30T15:51:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/de_LS\\\/soziale-stadtteilarbeit\\\/kultur-fuer-aeltere\\\/\",\"url\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/de_LS\\\/soziale-stadtteilarbeit\\\/kultur-fuer-aeltere\\\/\",\"name\":\"Kultur f\u00fcr \u00c4ltere - Volksbildungswerk Klarenthal e.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/de_LS\\\/#website\"},\"datePublished\":\"2025-02-27T21:07:02+00:00\",\"dateModified\":\"2025-07-30T15:51:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/de_LS\\\/soziale-stadtteilarbeit\\\/kultur-fuer-aeltere\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.klarenthal-vbw.de\\\/de_LS\\\/soziale-stadtteilarbeit\\\/kultur-fuer-aeltere\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/de_LS\\\/soziale-stadtteilarbeit\\\/kultur-fuer-aeltere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/de_LS\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soziale Stadtteilarbeit\",\"item\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/de_LS\\\/soziale-stadtteilarbeit\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kultur f\u00fcr \u00c4ltere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/de_LS\\\/#website\",\"url\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/de_LS\\\/\",\"name\":\"Volksbildungswerk Klarenthal e.V.\",\"description\":\"Chancen. Bildung. Perspektiven\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/de_LS\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/de_LS\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/de_LS\\\/#organization\",\"name\":\"Volksbildungswerk Klarenthal e.V.\",\"url\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/de_LS\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/de_LS\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo.svg\",\"caption\":\"Volksbildungswerk Klarenthal e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/de_LS\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kultur f\u00fcr \u00c4ltere - Volksbildungswerk Klarenthal e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.klarenthal-vbw.de\/de_LS\/soziale-stadtteilarbeit\/kultur-fuer-aeltere\/","og_locale":"de_DE","og_type":"article","og_title":"Kultur f\u00fcr \u00c4ltere - Volksbildungswerk Klarenthal e.V.","og_description":"Vielf\u00e4ltige Angebote f\u00fcr \u00e4ltere Menschen Wir schaffen Orte, die verbinden, Freude bringen und den Alltag bereichern \u2013besonders f\u00fcr \u00e4ltere Menschen.Deshalb bieten wir ein vielseitiges Programm.Seniorinnen und Senioren k\u00f6nnen sich kreativ bet\u00e4tigen,Neues entdecken und mit anderen in Kontakt kommen. Unsere Angebote Kreative Workshops: Malen, Handarbeiten, Sprachen\u2013 in unseren Kursen k\u00f6nnen Sie Ihre kreativen Seiten entfalten. Bewegung [&hellip;]","og_url":"https:\/\/www.klarenthal-vbw.de\/de_LS\/soziale-stadtteilarbeit\/kultur-fuer-aeltere\/","og_site_name":"Volksbildungswerk Klarenthal e.V.","article_modified_time":"2025-07-30T15:51:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.klarenthal-vbw.de\/de_LS\/soziale-stadtteilarbeit\/kultur-fuer-aeltere\/","url":"https:\/\/www.klarenthal-vbw.de\/de_LS\/soziale-stadtteilarbeit\/kultur-fuer-aeltere\/","name":"Kultur f\u00fcr \u00c4ltere - Volksbildungswerk Klarenthal e.V.","isPartOf":{"@id":"https:\/\/www.klarenthal-vbw.de\/de_LS\/#website"},"datePublished":"2025-02-27T21:07:02+00:00","dateModified":"2025-07-30T15:51:06+00:00","breadcrumb":{"@id":"https:\/\/www.klarenthal-vbw.de\/de_LS\/soziale-stadtteilarbeit\/kultur-fuer-aeltere\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.klarenthal-vbw.de\/de_LS\/soziale-stadtteilarbeit\/kultur-fuer-aeltere\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.klarenthal-vbw.de\/de_LS\/soziale-stadtteilarbeit\/kultur-fuer-aeltere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.klarenthal-vbw.de\/de_LS\/"},{"@type":"ListItem","position":2,"name":"Soziale Stadtteilarbeit","item":"https:\/\/www.klarenthal-vbw.de\/de_LS\/soziale-stadtteilarbeit\/"},{"@type":"ListItem","position":3,"name":"Kultur f\u00fcr \u00c4ltere"}]},{"@type":"WebSite","@id":"https:\/\/www.klarenthal-vbw.de\/de_LS\/#website","url":"https:\/\/www.klarenthal-vbw.de\/de_LS\/","name":"Volksbildungswerk Klarenthal e.V.","description":"Chancen. Bildung. Perspektiven","publisher":{"@id":"https:\/\/www.klarenthal-vbw.de\/de_LS\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.klarenthal-vbw.de\/de_LS\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.klarenthal-vbw.de\/de_LS\/#organization","name":"Volksbildungswerk Klarenthal e.V.","url":"https:\/\/www.klarenthal-vbw.de\/de_LS\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.klarenthal-vbw.de\/de_LS\/#\/schema\/logo\/image\/","url":"https:\/\/www.klarenthal-vbw.de\/wp-content\/uploads\/2025\/02\/logo.svg","contentUrl":"https:\/\/www.klarenthal-vbw.de\/wp-content\/uploads\/2025\/02\/logo.svg","caption":"Volksbildungswerk Klarenthal e.V."},"image":{"@id":"https:\/\/www.klarenthal-vbw.de\/de_LS\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.klarenthal-vbw.de\/de_LS\/wp-json\/wp\/v2\/pages\/8224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.klarenthal-vbw.de\/de_LS\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.klarenthal-vbw.de\/de_LS\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.klarenthal-vbw.de\/de_LS\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.klarenthal-vbw.de\/de_LS\/wp-json\/wp\/v2\/comments?post=8224"}],"version-history":[{"count":0,"href":"https:\/\/www.klarenthal-vbw.de\/de_LS\/wp-json\/wp\/v2\/pages\/8224\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.klarenthal-vbw.de\/de_LS\/wp-json\/wp\/v2\/pages\/8196"}],"wp:attachment":[{"href":"https:\/\/www.klarenthal-vbw.de\/de_LS\/wp-json\/wp\/v2\/media?parent=8224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.klarenthal-vbw.de\/de_LS\/wp-json\/wp\/v2\/categories?post=8224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.klarenthal-vbw.de\/de_LS\/wp-json\/wp\/v2\/tags?post=8224"},{"taxonomy":"folder","embeddable":true,"href":"https:\/\/www.klarenthal-vbw.de\/de_LS\/wp-json\/wp\/v2\/folder?post=8224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}