{"id":4870,"date":"2018-01-11T15:25:24","date_gmt":"2018-01-11T14:25:24","guid":{"rendered":"https:\/\/vbw.entwicklung-mediengewerk.de\/privacy-policy\/"},"modified":"2025-04-05T16:58:37","modified_gmt":"2025-04-05T14:58:37","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/www.klarenthal-vbw.de\/en\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4870\" class=\"elementor elementor-4870 elementor-75\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd6a7be e-flex e-con-boxed e-con e-parent\" data-id=\"bd6a7be\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9242782 elementor-widget elementor-widget-erecht24\" data-id=\"9242782\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"erecht24.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"erecht24-elementor-widget\"><div style=\"word-wrap: break-word;\">\n<h2>1. Datenschutz auf einen Blick<\/h2>\n<h3>Allgemeine Hinweise<\/h3> <p>Die folgenden Hinweise geben einen einfachen &Uuml;berblick dar&uuml;ber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers&ouml;nlich identifiziert werden k&ouml;nnen. Ausf&uuml;hrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef&uuml;hrten Datenschutzerkl&auml;rung.<\/p>\n<h3>Datenerfassung auf dieser Website<\/h3> <h4>Wer ist verantwortlich f&uuml;r die Datenerfassung auf dieser Website?<\/h4> <p>Die Datenverarbeitung auf dieser Website erfolgt durch den Websitebetreiber. Dessen Kontaktdaten k&ouml;nnen Sie dem Abschnitt &bdquo;Hinweis zur Verantwortlichen Stelle&ldquo; in dieser Datenschutzerkl&auml;rung entnehmen.<\/p> <h4>Wie erfassen wir Ihre Daten?<\/h4> <p>Ihre Daten werden zum einen dadurch erhoben, dass Sie uns diese mitteilen. Hierbei kann es sich z.&nbsp;B. um Daten handeln, die Sie in ein Kontaktformular eingeben.<\/p> <p>Andere Daten werden automatisch oder nach Ihrer Einwilligung beim Besuch der Website durch unsere IT-Systeme erfasst. Das sind vor allem technische Daten (z.&nbsp;B. Internetbrowser, Betriebssystem oder Uhrzeit des Seitenaufrufs). Die Erfassung dieser Daten erfolgt automatisch, sobald Sie diese Website betreten.<\/p> <h4>Wof&uuml;r nutzen wir Ihre Daten?<\/h4> <p>Ein Teil der Daten wird erhoben, um eine fehlerfreie Bereitstellung der Website zu gew&auml;hrleisten. Andere Daten k&ouml;nnen zur Analyse Ihres Nutzerverhaltens verwendet werden. Sofern &uuml;ber die Website Vertr&auml;ge geschlossen oder angebahnt werden k&ouml;nnen, werden die &uuml;bermittelten Daten auch f&uuml;r Vertragsangebote, Bestellungen oder sonstige Auftragsanfragen verarbeitet.<\/p> <h4>Welche Rechte haben Sie bez&uuml;glich Ihrer Daten?<\/h4> <p>Sie haben jederzeit das Recht, unentgeltlich Auskunft &uuml;ber Herkunft, Empf&auml;nger und Zweck Ihrer gespeicherten personenbezogenen Daten zu erhalten. Sie haben au&szlig;erdem ein Recht, die Berichtigung oder L&ouml;schung dieser Daten zu verlangen. Wenn Sie eine Einwilligung zur Datenverarbeitung erteilt haben, k&ouml;nnen Sie diese Einwilligung jederzeit f&uuml;r die Zukunft widerrufen. Au&szlig;erdem haben Sie das Recht, unter bestimmten Umst&auml;nden die Einschr&auml;nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Des Weiteren steht Ihnen ein Beschwerderecht bei der zust&auml;ndigen Aufsichtsbeh&ouml;rde zu.<\/p> <p>Hierzu sowie zu weiteren Fragen zum Thema Datenschutz k&ouml;nnen Sie sich jederzeit an uns wenden.<\/p>\n<h3>Analyse-Tools und Tools von Dritt&shy;anbietern<\/h3> <p>Beim Besuch dieser Website kann Ihr Surf-Verhalten statistisch ausgewertet werden. Das geschieht vor allem mit sogenannten Analyseprogrammen.<\/p> <p>Detaillierte Informationen zu diesen Analyseprogrammen finden Sie in der folgenden Datenschutzerkl&auml;rung.<\/p>\n<h2>2. Hosting<\/h2>\n<p>Wir hosten die Inhalte unserer Website bei folgendem Anbieter:<\/p>\n<h3>All-Inkl<\/h3> <p>Anbieter ist die ALL-INKL.COM - Neue Medien M&uuml;nnich, Inh. Ren&eacute; M&uuml;nnich, Hauptstra&szlig;e 68, 02742 Friedersdorf (nachfolgend All-Inkl). Details entnehmen Sie der Datenschutzerkl&auml;rung von All-Inkl: <a href=\"https:\/\/all-inkl.com\/datenschutzinformationen\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/all-inkl.com\/datenschutzinformationen\/<\/a>.<\/p> <p>Die Verwendung von All-Inkl erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Wir haben ein berechtigtes Interesse an einer m&ouml;glichst zuverl&auml;ssigen Darstellung unserer Website. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie&szlig;lich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und &sect; 25 Abs. 1 TDDDG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger&auml;t des Nutzers (z.&nbsp;B. Device-Fingerprinting) im Sinne des TDDDG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n\n<h4>Auftragsverarbeitung<\/h4> <p>Wir haben einen Vertrag &uuml;ber Auftragsverarbeitung (AVV) zur Nutzung des oben genannten Dienstes geschlossen. Hierbei handelt es sich um einen datenschutzrechtlich vorgeschriebenen Vertrag, der gew&auml;hrleistet, dass dieser die personenbezogenen Daten unserer Websitebesucher nur nach unseren Weisungen und unter Einhaltung der DSGVO verarbeitet.<\/p>\n<h2>3. Allgemeine Hinweise und Pflicht&shy;informationen<\/h2>\n<h3>Datenschutz<\/h3> <p>Die Betreiber dieser Seiten nehmen den Schutz Ihrer pers&ouml;nlichen Daten sehr ernst. Wir behandeln Ihre personenbezogenen Daten vertraulich und entsprechend den gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl&auml;rung.<\/p> <p>Wenn Sie diese Website benutzen, werden verschiedene personenbezogene Daten erhoben. Personenbezogene Daten sind Daten, mit denen Sie pers&ouml;nlich identifiziert werden k&ouml;nnen. Die vorliegende Datenschutzerkl&auml;rung erl&auml;utert, welche Daten wir erheben und wof&uuml;r wir sie nutzen. Sie erl&auml;utert auch, wie und zu welchem Zweck das geschieht.<\/p> <p>Wir weisen darauf hin, dass die Daten&uuml;bertragung im Internet (z.&nbsp;B. bei der Kommunikation per E-Mail) Sicherheitsl&uuml;cken aufweisen kann. Ein l&uuml;ckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m&ouml;glich.<\/p>\n<h3>Hinweis zur verantwortlichen Stelle<\/h3> <p>Die verantwortliche Stelle f&uuml;r die Datenverarbeitung auf dieser Website ist:<\/p> <p>Volksbildungswerk Klarenthal e.V.<br \/>\r\nGeschwister-Scholl-Stra&szlig;e 10<br \/>\r\n65197 Wiesbaden<\/p>\n\n<p>Telefon: 0611 72437920<br \/>\nE-Mail: info@klarenthal.org<\/p>\n <p>Verantwortliche Stelle ist die nat&uuml;rliche oder juristische Person, die allein oder gemeinsam mit anderen &uuml;ber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten (z.&nbsp;B. Namen, E-Mail-Adressen o. &Auml;.) entscheidet.<\/p>\n\n<h3>Speicherdauer<\/h3> <p>Soweit innerhalb dieser Datenschutzerkl&auml;rung keine speziellere Speicherdauer genannt wurde, verbleiben Ihre personenbezogenen Daten bei uns, bis der Zweck f&uuml;r die Datenverarbeitung entf&auml;llt. Wenn Sie ein berechtigtes L&ouml;schersuchen geltend machen oder eine Einwilligung zur Datenverarbeitung widerrufen, werden Ihre Daten gel&ouml;scht, sofern wir keine anderen rechtlich zul&auml;ssigen Gr&uuml;nde f&uuml;r die Speicherung Ihrer personenbezogenen Daten haben (z.&nbsp;B. steuer- oder handelsrechtliche Aufbewahrungsfristen); im letztgenannten Fall erfolgt die L&ouml;schung nach Fortfall dieser Gr&uuml;nde.<\/p>\n<h3>Allgemeine Hinweise zu den Rechtsgrundlagen der Datenverarbeitung auf dieser Website<\/h3> <p>Sofern Sie in die Datenverarbeitung eingewilligt haben, verarbeiten wir Ihre personenbezogenen Daten auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO bzw. Art. 9 Abs. 2 lit. a DSGVO, sofern besondere Datenkategorien nach Art. 9 Abs. 1 DSGVO verarbeitet werden. Im Falle einer ausdr&uuml;cklichen Einwilligung in die &Uuml;bertragung personenbezogener Daten in Drittstaaten erfolgt die Datenverarbeitung au&szlig;erdem auf Grundlage von Art. 49 Abs. 1 lit. a DSGVO. Sofern Sie in die Speicherung von Cookies oder in den Zugriff auf Informationen in Ihr Endger&auml;t (z.&nbsp;B. via Device-Fingerprinting) eingewilligt haben, erfolgt die Datenverarbeitung zus&auml;tzlich auf Grundlage von &sect; 25 Abs. 1 TDDDG. Die Einwilligung ist jederzeit widerrufbar. Sind Ihre Daten zur Vertragserf&uuml;llung oder zur Durchf&uuml;hrung vorvertraglicher Ma&szlig;nahmen erforderlich, verarbeiten wir Ihre Daten auf Grundlage des Art. 6 Abs. 1 lit. b DSGVO. Des Weiteren verarbeiten wir Ihre Daten, sofern diese zur Erf&uuml;llung einer rechtlichen Verpflichtung erforderlich sind auf Grundlage von Art. 6 Abs. 1 lit. c DSGVO. Die Datenverarbeitung kann ferner auf Grundlage unseres berechtigten Interesses nach Art. 6 Abs. 1 lit. f DSGVO erfolgen. &Uuml;ber die jeweils im Einzelfall einschl&auml;gigen Rechtsgrundlagen wird in den folgenden Abs&auml;tzen dieser Datenschutzerkl&auml;rung informiert.<\/p>\n<h3>Hinweis zur Datenweitergabe in datenschutzrechtlich nicht sichere Drittstaaten sowie die Weitergabe an US-Unternehmen, die nicht DPF-zertifiziert sind<\/h3> <p>Wir verwenden unter anderem Tools von Unternehmen mit Sitz in datenschutzrechtlich nicht sicheren Drittstaaten sowie US-Tools, deren Anbieter nicht nach dem EU-US-Data Privacy Framework (DPF) zertifiziert sind. Wenn diese Tools aktiv sind, k&ouml;nnen Ihre personenbezogene Daten in diese Staaten &uuml;bertragen und dort verarbeitet werden. Wir weisen darauf hin, dass in datenschutzrechtlich unsicheren Drittstaaten kein mit der EU vergleichbares Datenschutzniveau garantiert werden kann.<\/p> <p>Wir weisen darauf hin, dass die USA als sicherer Drittstaat grunds&auml;tzlich ein mit der EU vergleichbares Datenschutzniveau aufweisen. Eine Daten&uuml;bertragung in die USA ist danach zul&auml;ssig, wenn der Empf&auml;nger eine Zertifizierung unter dem &bdquo;EU-US Data Privacy Framework&ldquo; (DPF) besitzt oder &uuml;ber geeignete zus&auml;tzliche Garantien verf&uuml;gt. Informationen zu &Uuml;bermittlungen an Drittstaaten einschlie&szlig;lich der Datenempf&auml;nger finden Sie in dieser Datenschutzerkl&auml;rung.<\/p><h3>Empf\u00e4nger von personenbezogenen Daten<\/h3> <p>Im Rahmen unserer Gesch&auml;ftst&auml;tigkeit arbeiten wir mit verschiedenen externen Stellen zusammen. Dabei ist teilweise auch eine &Uuml;bermittlung von personenbezogenen Daten an diese externen Stellen erforderlich. Wir geben personenbezogene Daten nur dann an externe Stellen weiter, wenn dies im Rahmen einer Vertragserf&uuml;llung erforderlich ist, wenn wir gesetzlich hierzu verpflichtet sind (z.&nbsp;B. Weitergabe von Daten an Steuerbeh&ouml;rden), wenn wir ein berechtigtes Interesse nach Art. 6 Abs. 1 lit. f DSGVO an der Weitergabe haben oder wenn eine sonstige Rechtsgrundlage die Datenweitergabe erlaubt. Beim Einsatz von Auftragsverarbeitern geben wir personenbezogene Daten unserer Kunden nur auf Grundlage eines g&uuml;ltigen Vertrags &uuml;ber Auftragsverarbeitung weiter. Im Falle einer gemeinsamen Verarbeitung wird ein Vertrag &uuml;ber gemeinsame Verarbeitung geschlossen.<\/p>\n<h3>Widerruf Ihrer Einwilligung zur Datenverarbeitung<\/h3> <p>Viele Datenverarbeitungsvorg&auml;nge sind nur mit Ihrer ausdr&uuml;cklichen Einwilligung m&ouml;glich. Sie k&ouml;nnen eine bereits erteilte Einwilligung jederzeit widerrufen. Die Rechtm&auml;&szlig;igkeit der bis zum Widerruf erfolgten Datenverarbeitung bleibt vom Widerruf unber&uuml;hrt.<\/p>\n<h3>Widerspruchsrecht gegen die Datenerhebung in besonderen F&auml;llen sowie gegen Direktwerbung (Art. 21 DSGVO)<\/h3> <p>WENN DIE DATENVERARBEITUNG AUF GRUNDLAGE VON ART. 6 ABS. 1 LIT. E ODER F DSGVO ERFOLGT, HABEN SIE JEDERZEIT DAS RECHT, AUS GR&Uuml;NDEN, DIE SICH AUS IHRER BESONDEREN SITUATION ERGEBEN, GEGEN DIE VERARBEITUNG IHRER PERSONENBEZOGENEN DATEN WIDERSPRUCH EINZULEGEN; DIES GILT AUCH F&Uuml;R EIN AUF DIESE BESTIMMUNGEN GEST&Uuml;TZTES PROFILING. DIE JEWEILIGE RECHTSGRUNDLAGE, AUF DENEN EINE VERARBEITUNG BERUHT, ENTNEHMEN SIE DIESER DATENSCHUTZERKL&Auml;RUNG. WENN SIE WIDERSPRUCH EINLEGEN, WERDEN WIR IHRE BETROFFENEN PERSONENBEZOGENEN DATEN NICHT MEHR VERARBEITEN, ES SEI DENN, WIR K&Ouml;NNEN ZWINGENDE SCHUTZW&Uuml;RDIGE GR&Uuml;NDE F&Uuml;R DIE VERARBEITUNG NACHWEISEN, DIE IHRE INTERESSEN, RECHTE UND FREIHEITEN &Uuml;BERWIEGEN ODER DIE VERARBEITUNG DIENT DER GELTENDMACHUNG, AUS&Uuml;BUNG ODER VERTEIDIGUNG VON RECHTSANSPR&Uuml;CHEN (WIDERSPRUCH NACH ART. 21 ABS. 1 DSGVO).<\/p> <p>WERDEN IHRE PERSONENBEZOGENEN DATEN VERARBEITET, UM DIREKTWERBUNG ZU BETREIBEN, SO HABEN SIE DAS RECHT, JEDERZEIT WIDERSPRUCH GEGEN DIE VERARBEITUNG SIE BETREFFENDER PERSONENBEZOGENER DATEN ZUM ZWECKE DERARTIGER WERBUNG EINZULEGEN; DIES GILT AUCH F&Uuml;R DAS PROFILING, SOWEIT ES MIT SOLCHER DIREKTWERBUNG IN VERBINDUNG STEHT. WENN SIE WIDERSPRECHEN, WERDEN IHRE PERSONENBEZOGENEN DATEN ANSCHLIESSEND NICHT MEHR ZUM ZWECKE DER DIREKTWERBUNG VERWENDET (WIDERSPRUCH NACH ART. 21 ABS. 2 DSGVO).<\/p>\n<h3>Beschwerde&shy;recht bei der zust&auml;ndigen Aufsichts&shy;beh&ouml;rde<\/h3> <p>Im Falle von Verst&ouml;&szlig;en gegen die DSGVO steht den Betroffenen ein Beschwerderecht bei einer Aufsichtsbeh&ouml;rde, insbesondere in dem Mitgliedstaat ihres gew&ouml;hnlichen Aufenthalts, ihres Arbeitsplatzes oder des Orts des mutma&szlig;lichen Versto&szlig;es zu. Das Beschwerderecht besteht unbeschadet anderweitiger verwaltungsrechtlicher oder gerichtlicher Rechtsbehelfe.<\/p>\n<h3>Recht auf Daten&shy;&uuml;bertrag&shy;barkeit<\/h3> <p>Sie haben das Recht, Daten, die wir auf Grundlage Ihrer Einwilligung oder in Erf&uuml;llung eines Vertrags automatisiert verarbeiten, an sich oder an einen Dritten in einem g&auml;ngigen, maschinenlesbaren Format aush&auml;ndigen zu lassen. Sofern Sie die direkte &Uuml;bertragung der Daten an einen anderen Verantwortlichen verlangen, erfolgt dies nur, soweit es technisch machbar ist.<\/p>\n<h3>Auskunft, Berichtigung und L&ouml;schung<\/h3> <p>Sie haben im Rahmen der geltenden gesetzlichen Bestimmungen jederzeit das Recht auf unentgeltliche Auskunft &uuml;ber Ihre gespeicherten personenbezogenen Daten, deren Herkunft und Empf&auml;nger und den Zweck der Datenverarbeitung und ggf. ein Recht auf Berichtigung oder L&ouml;schung dieser Daten. Hierzu sowie zu weiteren Fragen zum Thema personenbezogene Daten k&ouml;nnen Sie sich jederzeit an uns wenden.<\/p>\n<h3>Recht auf Einschr&auml;nkung der Verarbeitung<\/h3> <p>Sie haben das Recht, die Einschr&auml;nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Hierzu k&ouml;nnen Sie sich jederzeit an uns wenden. Das Recht auf Einschr&auml;nkung der Verarbeitung besteht in folgenden F&auml;llen:<\/p> <ul> <li>Wenn Sie die Richtigkeit Ihrer bei uns gespeicherten personenbezogenen Daten bestreiten, ben&ouml;tigen wir in der Regel Zeit, um dies zu &uuml;berpr&uuml;fen. F&uuml;r die Dauer der Pr&uuml;fung haben Sie das Recht, die Einschr&auml;nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li> <li>Wenn die Verarbeitung Ihrer personenbezogenen Daten unrechtm&auml;&szlig;ig geschah\/geschieht, k&ouml;nnen Sie statt der L&ouml;schung die Einschr&auml;nkung der Datenverarbeitung verlangen.<\/li> <li>Wenn wir Ihre personenbezogenen Daten nicht mehr ben&ouml;tigen, Sie sie jedoch zur Aus&uuml;bung, Verteidigung oder Geltendmachung von Rechtsanspr&uuml;chen ben&ouml;tigen, haben Sie das Recht, statt der L&ouml;schung die Einschr&auml;nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li> <li>Wenn Sie einen Widerspruch nach Art. 21 Abs. 1 DSGVO eingelegt haben, muss eine Abw&auml;gung zwischen Ihren und unseren Interessen vorgenommen werden. Solange noch nicht feststeht, wessen Interessen &uuml;berwiegen, haben Sie das Recht, die Einschr&auml;nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li> <\/ul> <p>Wenn Sie die Verarbeitung Ihrer personenbezogenen Daten eingeschr&auml;nkt haben, d&uuml;rfen diese Daten &ndash; von ihrer Speicherung abgesehen &ndash; nur mit Ihrer Einwilligung oder zur Geltendmachung, Aus&uuml;bung oder Verteidigung von Rechtsanspr&uuml;chen oder zum Schutz der Rechte einer anderen nat&uuml;rlichen oder juristischen Person oder aus Gr&uuml;nden eines wichtigen &ouml;ffentlichen Interesses der Europ&auml;ischen Union oder eines Mitgliedstaats verarbeitet werden.<\/p>\n<h3>SSL- bzw. TLS-Verschl&uuml;sselung<\/h3> <p>Diese Seite nutzt aus Sicherheitsgr&uuml;nden und zum Schutz der &Uuml;bertragung vertraulicher Inhalte, wie zum Beispiel Bestellungen oder Anfragen, die Sie an uns als Seitenbetreiber senden, eine SSL- bzw. TLS-Verschl&uuml;sselung. Eine verschl&uuml;sselte Verbindung erkennen Sie daran, dass die Adresszeile des Browsers von &bdquo;http:\/\/&ldquo; auf &bdquo;https:\/\/&ldquo; wechselt und an dem Schloss-Symbol in Ihrer Browserzeile.<\/p> <p>Wenn die SSL- bzw. TLS-Verschl&uuml;sselung aktiviert ist, k&ouml;nnen die Daten, die Sie an uns &uuml;bermitteln, nicht von Dritten mitgelesen werden.<\/p>\n<h3>Verschl&uuml;sselter Zahlungsverkehr auf dieser Website<\/h3> <p>Besteht nach dem Abschluss eines kostenpflichtigen Vertrags eine Verpflichtung, uns Ihre Zahlungsdaten (z.&nbsp;B. Kontonummer bei Einzugserm&auml;chtigung) zu &uuml;bermitteln, werden diese Daten zur Zahlungsabwicklung ben&ouml;tigt.<\/p> <p>Der Zahlungsverkehr &uuml;ber die g&auml;ngigen Zahlungsmittel (Visa\/MasterCard, Lastschriftverfahren) erfolgt ausschlie&szlig;lich &uuml;ber eine verschl&uuml;sselte SSL- bzw. TLS-Verbindung. Eine verschl&uuml;sselte Verbindung erkennen Sie daran, dass die Adresszeile des Browsers von &bdquo;http:\/\/&ldquo; auf &bdquo;https:\/\/&ldquo; wechselt und an dem Schloss-Symbol in Ihrer Browserzeile.<\/p> <p>Bei verschl&uuml;sselter Kommunikation k&ouml;nnen Ihre Zahlungsdaten, die Sie an uns &uuml;bermitteln, nicht von Dritten mitgelesen werden.<\/p>\n<h3>Widerspruch gegen Werbe-E-Mails<\/h3> <p>Der Nutzung von im Rahmen der Impressumspflicht ver&ouml;ffentlichten Kontaktdaten zur &Uuml;bersendung von nicht ausdr&uuml;cklich angeforderter Werbung und Informationsmaterialien wird hiermit widersprochen. Die Betreiber der Seiten behalten sich ausdr&uuml;cklich rechtliche Schritte im Falle der unverlangten Zusendung von Werbeinformationen, etwa durch Spam-E-Mails, vor.<\/p>\n<h2>4. Datenerfassung auf dieser Website<\/h2>\n<h3>Cookies<\/h3> <p>Unsere Internetseiten verwenden so genannte &bdquo;Cookies&ldquo;. Cookies sind kleine Datenpakete und richten auf Ihrem Endger&auml;t keinen Schaden an. Sie werden entweder vor&uuml;bergehend f&uuml;r die Dauer einer Sitzung (Session-Cookies) oder dauerhaft (permanente Cookies) auf Ihrem Endger&auml;t gespeichert. Session-Cookies werden nach Ende Ihres Besuchs automatisch gel&ouml;scht. Permanente Cookies bleiben auf Ihrem Endger&auml;t gespeichert, bis Sie diese selbst l&ouml;schen oder eine automatische L&ouml;schung durch Ihren Webbrowser erfolgt.<\/p> <p>Cookies k&ouml;nnen von uns (First-Party-Cookies) oder von Drittunternehmen stammen (sog. Third-Party-Cookies). Third-Party-Cookies erm&ouml;glichen die Einbindung bestimmter Dienstleistungen von Drittunternehmen innerhalb von Webseiten (z.&nbsp;B. Cookies zur Abwicklung von Zahlungsdienstleistungen).<\/p> <p>Cookies haben verschiedene Funktionen. Zahlreiche Cookies sind technisch notwendig, da bestimmte Webseitenfunktionen ohne diese nicht funktionieren w&uuml;rden (z.&nbsp;B. die Warenkorbfunktion oder die Anzeige von Videos). Andere Cookies k&ouml;nnen zur Auswertung des Nutzerverhaltens oder zu Werbezwecken verwendet werden.<\/p> <p>Cookies, die zur Durchf&uuml;hrung des elektronischen Kommunikationsvorgangs, zur Bereitstellung bestimmter, von Ihnen erw&uuml;nschter Funktionen (z.&nbsp;B. f&uuml;r die Warenkorbfunktion) oder zur Optimierung der Website (z.&nbsp;B. Cookies zur Messung des Webpublikums) erforderlich sind (notwendige Cookies), werden auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO gespeichert, sofern keine andere Rechtsgrundlage angegeben wird. Der Websitebetreiber hat ein berechtigtes Interesse an der Speicherung von notwendigen Cookies zur technisch fehlerfreien und optimierten Bereitstellung seiner Dienste. Sofern eine Einwilligung zur Speicherung von Cookies und vergleichbaren Wiedererkennungstechnologien abgefragt wurde, erfolgt die Verarbeitung ausschlie&szlig;lich auf Grundlage dieser Einwilligung (Art. 6 Abs. 1 lit. a DSGVO und &sect; 25 Abs. 1 TDDDG); die Einwilligung ist jederzeit widerrufbar.<\/p> <p>Sie k&ouml;nnen Ihren Browser so einstellen, dass Sie &uuml;ber das Setzen von Cookies informiert werden und Cookies nur im Einzelfall erlauben, die Annahme von Cookies f&uuml;r bestimmte F&auml;lle oder generell ausschlie&szlig;en sowie das automatische L&ouml;schen der Cookies beim Schlie&szlig;en des Browsers aktivieren. Bei der Deaktivierung von Cookies kann die Funktionalit&auml;t dieser Website eingeschr&auml;nkt sein.<\/p> <p>Welche Cookies und Dienste auf dieser Website eingesetzt werden, k&ouml;nnen Sie dieser Datenschutzerkl&auml;rung entnehmen.<\/p>\n<h3>Einwilligung mit Borlabs Cookie<\/h3> <p>Unsere Website nutzt die Consent-Technologie von Borlabs Cookie, um Ihre Einwilligung zur Speicherung bestimmter Cookies in Ihrem Browser oder zum Einsatz bestimmter Technologien einzuholen und diese datenschutzkonform zu dokumentieren. Anbieter dieser Technologie ist die Borlabs GmbH, R&uuml;benkamp 32, 22305 Hamburg (im Folgenden Borlabs).<\/p> <p>Wenn Sie unsere Website betreten, wird ein Borlabs-Cookie in Ihrem Browser gespeichert, in dem die von Ihnen erteilten Einwilligungen oder der Widerruf dieser Einwilligungen gespeichert werden. Diese Daten werden nicht an den Anbieter von Borlabs Cookie weitergegeben.<\/p> <p>Die erfassten Daten werden gespeichert, bis Sie uns zur L&ouml;schung auffordern bzw. das Borlabs-Cookie selbst l&ouml;schen oder der Zweck f&uuml;r die Datenspeicherung entf&auml;llt. Zwingende gesetzliche Aufbewahrungsfristen bleiben unber&uuml;hrt. Details zur Datenverarbeitung von Borlabs Cookie finden Sie unter <a href=\"https:\/\/de.borlabs.io\/kb\/welche-daten-speichert-borlabs-cookie\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de.borlabs.io\/kb\/welche-daten-speichert-borlabs-cookie\/<\/a>.<\/p> <p>Der Einsatz der Borlabs-Cookie-Consent-Technologie erfolgt, um die gesetzlich vorgeschriebenen Einwilligungen f&uuml;r den Einsatz von Cookies einzuholen. Rechtsgrundlage hierf&uuml;r ist Art. 6 Abs. 1 lit. c DSGVO.<\/p>\n<h3>Server-Log-Dateien<\/h3> <p>Der Provider der Seiten erhebt und speichert automatisch Informationen in so genannten Server-Log-Dateien, die Ihr Browser automatisch an uns &uuml;bermittelt. Dies sind:<\/p> <ul> <li>Browsertyp und Browserversion<\/li> <li>verwendetes Betriebssystem<\/li> <li>Referrer URL<\/li> <li>Hostname des zugreifenden Rechners<\/li> <li>Uhrzeit der Serveranfrage<\/li> <li>IP-Adresse<\/li> <\/ul> <p>Eine Zusammenf&uuml;hrung dieser Daten mit anderen Datenquellen wird nicht vorgenommen.<\/p> <p>Die Erfassung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an der technisch fehlerfreien Darstellung und der Optimierung seiner Website &ndash; hierzu m&uuml;ssen die Server-Log-Files erfasst werden.<\/p>\n<h3>Kontaktformular<\/h3> <p>Wenn Sie uns per Kontaktformular Anfragen zukommen lassen, werden Ihre Angaben aus dem Anfrageformular inklusive der von Ihnen dort angegebenen Kontaktdaten zwecks Bearbeitung der Anfrage und f&uuml;r den Fall von Anschlussfragen bei uns gespeichert. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.<\/p> <p>Die Verarbeitung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO, sofern Ihre Anfrage mit der Erf&uuml;llung eines Vertrags zusammenh&auml;ngt oder zur Durchf&uuml;hrung vorvertraglicher Ma&szlig;nahmen erforderlich ist. In allen &uuml;brigen F&auml;llen beruht die Verarbeitung auf unserem berechtigten Interesse an der effektiven Bearbeitung der an uns gerichteten Anfragen (Art. 6 Abs. 1 lit. f DSGVO) oder auf Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO) sofern diese abgefragt wurde; die Einwilligung ist jederzeit widerrufbar.<\/p> <p>Die von Ihnen im Kontaktformular eingegebenen Daten verbleiben bei uns, bis Sie uns zur L&ouml;schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f&uuml;r die Datenspeicherung entf&auml;llt (z.&nbsp;B. nach abgeschlossener Bearbeitung Ihrer Anfrage). Zwingende gesetzliche Bestimmungen &ndash; insbesondere Aufbewahrungsfristen &ndash; bleiben unber&uuml;hrt.<\/p>\n<h3>Anfrage per E-Mail, Telefon oder Telefax<\/h3> <p>Wenn Sie uns per E-Mail, Telefon oder Telefax kontaktieren, wird Ihre Anfrage inklusive aller daraus hervorgehenden personenbezogenen Daten (Name, Anfrage) zum Zwecke der Bearbeitung Ihres Anliegens bei uns gespeichert und verarbeitet. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.<\/p> <p>Die Verarbeitung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO, sofern Ihre Anfrage mit der Erf&uuml;llung eines Vertrags zusammenh&auml;ngt oder zur Durchf&uuml;hrung vorvertraglicher Ma&szlig;nahmen erforderlich ist. In allen &uuml;brigen F&auml;llen beruht die Verarbeitung auf unserem berechtigten Interesse an der effektiven Bearbeitung der an uns gerichteten Anfragen (Art. 6 Abs. 1 lit. f DSGVO) oder auf Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO) sofern diese abgefragt wurde; die Einwilligung ist jederzeit widerrufbar.<\/p> <p>Die von Ihnen an uns per Kontaktanfragen &uuml;bersandten Daten verbleiben bei uns, bis Sie uns zur L&ouml;schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f&uuml;r die Datenspeicherung entf&auml;llt (z.&nbsp;B. nach abgeschlossener Bearbeitung Ihres Anliegens). Zwingende gesetzliche Bestimmungen &ndash; insbesondere gesetzliche Aufbewahrungsfristen &ndash; bleiben unber&uuml;hrt.<\/p>\n<h3>Kommunikation via WhatsApp<\/h3> <p>F&uuml;r die Kommunikation mit unseren Kunden und sonstigen Dritten nutzen wir unter anderem den Instant-Messaging-Dienst WhatsApp. Anbieter ist die WhatsApp Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irland.<\/p> <p>Die Kommunikation erfolgt &uuml;ber eine Ende-zu-Ende-Verschl&uuml;sselung (Peer-to-Peer), die verhindert, dass WhatsApp oder sonstige Dritte Zugriff auf die Kommunikationsinhalte erlangen k&ouml;nnen. WhatsApp erh&auml;lt jedoch Zugriff auf Metadaten, die im Zuge des Kommunikationsvorgangs entstehen (z.&nbsp;B. Absender, Empf&auml;nger und Zeitpunkt). Wir weisen ferner darauf hin, dass WhatsApp nach eigener Aussage, personenbezogene Daten seiner Nutzer mit seiner in den USA ans&auml;ssigen Konzernmutter Meta teilt. Weitere Details zur Datenverarbeitung finden Sie in der Datenschutzrichtlinie von WhatsApp unter: <a href=\"https:\/\/www.whatsapp.com\/legal\/#privacy-policy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.whatsapp.com\/legal\/#privacy-policy<\/a>.<\/p> <p>Der Einsatz von WhatsApp erfolgt auf Grundlage unseres berechtigten Interesses an einer m&ouml;glichst schnellen und effektiven Kommunikation mit Kunden, Interessenten und sonstigen Gesch&auml;fts- und Vertragspartnern (Art. 6 Abs. 1 lit. f DSGVO). Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Datenverarbeitung ausschlie&szlig;lich auf Grundlage der Einwilligung; diese ist jederzeit mit Wirkung f&uuml;r die Zukunft widerrufbar.<\/p> <p>Die zwischen Ihnen und uns auf WhatsApp ausgetauschten Kommunikationsinhalte verbleiben bei uns, bis Sie uns zur L&ouml;schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f&uuml;r die Datenspeicherung entf&auml;llt (z.&nbsp;B. nach abgeschlossener Bearbeitung Ihrer Anfrage). Zwingende gesetzliche Bestimmungen &ndash; insbesondere Aufbewahrungsfristen &ndash; bleiben unber&uuml;hrt.<\/p>\n<p>Das Unternehmen verf&uuml;gt &uuml;ber eine Zertifizierung nach dem &bdquo;EU-US Data Privacy Framework&ldquo; (DPF). Der DPF ist ein &Uuml;bereinkommen zwischen der Europ&auml;ischen Union und den USA, der die Einhaltung europ&auml;ischer Datenschutzstandards bei Datenverarbeitungen in den USA gew&auml;hrleisten soll. Jedes nach dem DPF zertifizierte Unternehmen verpflichtet sich, diese Datenschutzstandards einzuhalten. Weitere Informationen hierzu erhalten Sie vom Anbieter unter folgendem Link: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/7735\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/7735<\/a>.<\/p>\n<p>Wir nutzen WhatsApp in der Variante &bdquo;WhatsApp Business&ldquo;.<\/p> <p>Die Daten&uuml;bertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest&uuml;tzt. Details finden Sie hier: <a href=\"https:\/\/www.whatsapp.com\/legal\/business-data-transfer-addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.whatsapp.com\/legal\/business-data-transfer-addendum<\/a>.<\/p>\n<p>Wir haben unsere WhatsApp-Accounts so eingestellt, dass es keinen automatischen Datenabgleich mit dem Adressbuch auf den im Einsatz befindlichen Smartphones macht.<\/p>\n<p>Wir haben einen Vertrag &uuml;ber Auftragsverarbeitung (AVV) mit dem oben genannten Anbieter geschlossen.<\/p>\n<h2>5. Analyse-Tools und Werbung<\/h2>\n<h3>Google Analytics<\/h3> <p>Diese Website nutzt Funktionen des Webanalysedienstes Google Analytics. Anbieter ist die Google Ireland Limited (&bdquo;Google&ldquo;), Gordon House, Barrow Street, Dublin 4, Irland.<\/p> <p>Google Analytics erm&ouml;glicht es dem Websitebetreiber, das Verhalten der Websitebesucher zu analysieren. Hierbei erh&auml;lt der Websitebetreiber verschiedene Nutzungsdaten, wie z.&nbsp;B. Seitenaufrufe, Verweildauer, verwendete Betriebssysteme und Herkunft des Nutzers. Diese Daten werden dem jeweiligen Endger\u00e4t des Users zugeordnet. Eine Zuordnung zu einer User-ID erfolgt nicht.<\/p> <p>Des Weiteren k&ouml;nnen wir mit Google Analytics u.&nbsp;a. Ihre Maus- und Scrollbewegungen und Klicks aufzeichnen. Ferner verwendet Google Analytics verschiedene Modellierungsans&auml;tze, um die erfassten Datens&auml;tze zu erg&auml;nzen und setzt Machine-Learning-Technologien bei der Datenanalyse ein.<\/p>\n <p>Google Analytics verwendet Technologien, die die Wiedererkennung des Nutzers zum Zwecke der Analyse des Nutzerverhaltens erm&ouml;glichen (z.&nbsp;B. Cookies oder Device-Fingerprinting). Die von Google erfassten Informationen &uuml;ber die Benutzung dieser Website werden in der Regel an einen Server von Google in den USA &uuml;bertragen und dort gespeichert.<\/p> <p>Die Nutzung dieses Dienstes erfolgt auf Grundlage Ihrer Einwilligung nach Art. 6 Abs. 1 lit. a DSGVO und &sect; 25 Abs. 1 TDDDG. Die Einwilligung ist jederzeit widerrufbar.<\/p> <p>Die Daten&uuml;bertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest&uuml;tzt. Details finden Sie hier: <a href=\"https:\/\/privacy.google.com\/businesses\/controllerterms\/mccs\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacy.google.com\/businesses\/controllerterms\/mccs\/<\/a>.<\/p> <p>Das Unternehmen verf&uuml;gt &uuml;ber eine Zertifizierung nach dem &bdquo;EU-US Data Privacy Framework&ldquo; (DPF). Der DPF ist ein &Uuml;bereinkommen zwischen der Europ&auml;ischen Union und den USA, der die Einhaltung europ&auml;ischer Datenschutzstandards bei Datenverarbeitungen in den USA gew&auml;hrleisten soll. Jedes nach dem DPF zertifizierte Unternehmen verpflichtet sich, diese Datenschutzstandards einzuhalten. Weitere Informationen hierzu erhalten Sie vom Anbieter unter folgendem Link: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h4>IP Anonymisierung<\/h4> <p>Die Google Analytics IP-Anonymisierung ist aktiviert. Dadurch wird Ihre IP-Adresse von Google innerhalb von Mitgliedstaaten der Europ&auml;ischen Union oder in anderen Vertragsstaaten des Abkommens &uuml;ber den Europ&auml;ischen Wirtschaftsraum vor der &Uuml;bermittlung in die USA gek&uuml;rzt. Nur in Ausnahmef&auml;llen wird die volle IP-Adresse an einen Server von Google in den USA &uuml;bertragen und dort gek&uuml;rzt. Im Auftrag des Betreibers dieser Website wird Google diese Informationen benutzen, um Ihre Nutzung der Website auszuwerten, um Reports &uuml;ber die Websiteaktivit&auml;ten zusammenzustellen und um weitere mit der Websitenutzung und der Internetnutzung verbundene Dienstleistungen gegen&uuml;ber dem Websitebetreiber zu erbringen. Die im Rahmen von Google Analytics von Ihrem Browser &uuml;bermittelte IP-Adresse wird nicht mit anderen Daten von Google zusammengef&uuml;hrt.<\/p>\n <h4>Browser Plugin<\/h4> <p>Sie k&ouml;nnen die Erfassung und Verarbeitung Ihrer Daten durch Google verhindern, indem Sie das unter dem folgenden Link verf&uuml;gbare Browser-Plugin herunterladen und installieren: <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/a>.<\/p> <p>Mehr Informationen zum Umgang mit Nutzerdaten bei Google Analytics finden Sie in der Datenschutzerkl&auml;rung von Google: <a href=\"https:\/\/support.google.com\/analytics\/answer\/6004245?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/support.google.com\/analytics\/answer\/6004245?hl=de<\/a>.<\/p><h4>Auftragsverarbeitung<\/h4> <p>Wir haben mit Google einen Vertrag zur Auftragsverarbeitung abgeschlossen und setzen die strengen Vorgaben der deutschen Datenschutzbeh&ouml;rden bei der Nutzung von Google Analytics vollst&auml;ndig um.<\/p>\n<h2>6. Newsletter<\/h2>\n<h3>Newsletter&shy;daten<\/h3> <p>Wenn Sie den auf der Website angebotenen Newsletter beziehen m&ouml;chten, ben&ouml;tigen wir von Ihnen eine E-Mail-Adresse sowie Informationen, welche uns die &Uuml;berpr&uuml;fung gestatten, dass Sie der Inhaber der angegebenen E-Mail-Adresse sind und mit dem Empfang des Newsletters einverstanden sind. Weitere Daten werden nicht bzw. nur auf freiwilliger Basis erhoben. Diese Daten verwenden wir ausschlie&szlig;lich f&uuml;r den Versand der angeforderten Informationen und geben diese nicht an Dritte weiter.<\/p> <p>Die Verarbeitung der in das Newsletteranmeldeformular eingegebenen Daten erfolgt ausschlie&szlig;lich auf Grundlage Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO). Die erteilte Einwilligung zur Speicherung der Daten, der E-Mail-Adresse sowie deren Nutzung zum Versand des Newsletters k&ouml;nnen Sie jederzeit widerrufen, etwa &uuml;ber den &bdquo;Austragen&ldquo;-Link im Newsletter. Die Rechtm&auml;&szlig;igkeit der bereits erfolgten Datenverarbeitungsvorg&auml;nge bleibt vom Widerruf unber&uuml;hrt.<\/p> <p>Die von Ihnen zum Zwecke des Newsletter-Bezugs bei uns hinterlegten Daten werden von uns bis zu Ihrer Austragung aus dem Newsletter bei uns bzw. dem Newsletterdiensteanbieter gespeichert und nach der Abbestellung des Newsletters oder nach Zweckfortfall aus der Newsletterverteilerliste gel&ouml;scht. Wir behalten uns vor, E-Mail-Adressen aus unserem Newsletterverteiler nach eigenem Ermessen im Rahmen unseres berechtigten Interesses nach Art. 6 Abs. 1 lit. f DSGVO zu l&ouml;schen oder zu sperren.<\/p> <p>Daten, die zu anderen Zwecken bei uns gespeichert wurden, bleiben hiervon unber&uuml;hrt.<\/p> <p>Nach Ihrer Austragung aus der Newsletterverteilerliste wird Ihre E-Mail-Adresse bei uns bzw. dem Newsletterdiensteanbieter ggf. in einer Blacklist gespeichert, sofern dies zur Verhinderung k&uuml;nftiger Mailings erforderlich ist. Die Daten aus der Blacklist werden nur f&uuml;r diesen Zweck verwendet und nicht mit anderen Daten zusammengef&uuml;hrt. Dies dient sowohl Ihrem Interesse als auch unserem Interesse an der Einhaltung der gesetzlichen Vorgaben beim Versand von Newslettern (berechtigtes Interesse im Sinne des Art. 6 Abs. 1 lit. f DSGVO). Die Speicherung in der Blacklist ist zeitlich nicht befristet. <strong>Sie k&ouml;nnen der Speicherung widersprechen, sofern Ihre Interessen unser berechtigtes Interesse &uuml;berwiegen.<\/strong><\/p>\n<h2>7. Plugins und Tools<\/h2>\n<h3>YouTube mit erweitertem Datenschutz<\/h3> <p>Diese Website bindet Videos der Website YouTube ein. Betreiber der Website ist die Google Ireland Limited (&bdquo;Google&rdquo;), Gordon House, Barrow Street, Dublin 4, Irland.<\/p> <p>Wenn Sie eine dieser Website besuchen, auf denen YouTube eingebunden ist, wird eine Verbindung zu den Servern von YouTube hergestellt. Dabei wird dem YouTube-Server mitgeteilt, welche unserer Seiten Sie besucht haben. Wenn Sie in Ihrem YouTube-Account eingeloggt sind, erm&ouml;glichen Sie YouTube, Ihr Surfverhalten direkt Ihrem pers&ouml;nlichen Profil zuzuordnen. Dies k&ouml;nnen Sie verhindern, indem Sie sich aus Ihrem YouTube-Account ausloggen.<\/p> <p>Wir nutzen YouTube im erweiterten Datenschutzmodus. Videos, die im erweiterten Datenschutzmodus abgespielt werden, werden nach Aussage von YouTube nicht zur Personalisierung des Surfens auf YouTube eingesetzt. Anzeigen, die im erweiterten Datenschutzmodus ausgespielt werden, sind ebenfalls nicht personalisiert. Im erweiterten Datenschutzmodus werden keine Cookies gesetzt. Stattdessen werden jedoch sogenannte Local Storage Elemente im Browser des Users gespeichert, die &auml;hnlich wie Cookies personenbezogene Daten beinhalten und zur Wiedererkennung eingesetzt werden k&ouml;nnen. Details zum erweiterten Datenschutzmodus finden Sie hier: <a href=\"https:\/\/support.google.com\/youtube\/answer\/171780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/support.google.com\/youtube\/answer\/171780<\/a>.<\/p> <p>Gegebenenfalls k&ouml;nnen nach der Aktivierung eines YouTube-Videos weitere Datenverarbeitungsvorg&auml;nge ausgel&ouml;st werden, auf die wir keinen Einfluss haben.<\/p> <p>Die Nutzung von YouTube erfolgt im Interesse einer ansprechenden Darstellung unserer Online-Angebote. Dies stellt ein berechtigtes Interesse im Sinne von Art. 6 Abs. 1 lit. f DSGVO dar. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie&szlig;lich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und &sect; 25 Abs. 1 TDDDG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger&auml;t des Nutzers (z.&nbsp;B. Device-Fingerprinting) im Sinne des TDDDG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p> <p>Weitere Informationen &uuml;ber Datenschutz bei YouTube finden Sie in deren Datenschutzerkl&auml;rung unter: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<p>Das Unternehmen verf&uuml;gt &uuml;ber eine Zertifizierung nach dem &bdquo;EU-US Data Privacy Framework&ldquo; (DPF). Der DPF ist ein &Uuml;bereinkommen zwischen der Europ&auml;ischen Union und den USA, der die Einhaltung europ&auml;ischer Datenschutzstandards bei Datenverarbeitungen in den USA gew&auml;hrleisten soll. Jedes nach dem DPF zertifizierte Unternehmen verpflichtet sich, diese Datenschutzstandards einzuhalten. Weitere Informationen hierzu erhalten Sie vom Anbieter unter folgendem Link: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h3>Google Fonts (lokales Hosting)<\/h3> <p>Diese Seite nutzt zur einheitlichen Darstellung von Schriftarten so genannte Google Fonts, die von Google bereitgestellt werden. Die Google Fonts sind lokal installiert. Eine Verbindung zu Servern von Google findet dabei nicht statt.<\/p> <p>Weitere Informationen zu Google Fonts finden Sie unter <a href=\"https:\/\/developers.google.com\/fonts\/faq\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/developers.google.com\/fonts\/faq<\/a> und in der Datenschutzerkl&auml;rung von Google: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<h3>Google Maps<\/h3> <p>Diese Seite nutzt den Kartendienst Google Maps. Anbieter ist die Google Ireland Limited (&bdquo;Google&ldquo;), Gordon House, Barrow Street, Dublin 4, Irland. Mit Hilfe dieses Dienstes k&ouml;nnen wir Kartenmaterial auf unserer Website einbinden.<\/p> <p>Zur Nutzung der Funktionen von Google Maps ist es notwendig, Ihre IP-Adresse zu speichern. Diese Informationen werden in der Regel an einen Server von Google in den USA &uuml;bertragen und dort gespeichert. Der Anbieter dieser Seite hat keinen Einfluss auf diese Daten&uuml;bertragung. Wenn Google Maps aktiviert ist, kann Google zum Zwecke der einheitlichen Darstellung der Schriftarten Google Fonts verwenden. Beim Aufruf von Google Maps l&auml;dt Ihr Browser die ben&ouml;tigten Web Fonts in ihren Browsercache, um Texte und Schriftarten korrekt anzuzeigen.<\/p> <p>Die Nutzung von Google Maps erfolgt im Interesse einer ansprechenden Darstellung unserer Online-Angebote und an einer leichten Auffindbarkeit der von uns auf der Website angegebenen Orte. Dies stellt ein berechtigtes Interesse im Sinne von Art. 6 Abs. 1 lit. f DSGVO dar. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie&szlig;lich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und &sect; 25 Abs. 1 TDDDG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger&auml;t des Nutzers (z.&nbsp;B. Device-Fingerprinting) im Sinne des TDDDG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p> <p>Die Daten&uuml;bertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest&uuml;tzt. Details finden Sie hier: <a href=\"https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/<\/a> und <a href=\"https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/sccs\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/sccs\/<\/a>.<\/p> <p>Mehr Informationen zum Umgang mit Nutzerdaten finden Sie in der Datenschutzerkl&auml;rung von Google: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<p>Das Unternehmen verf&uuml;gt &uuml;ber eine Zertifizierung nach dem &bdquo;EU-US Data Privacy Framework&ldquo; (DPF). Der DPF ist ein &Uuml;bereinkommen zwischen der Europ&auml;ischen Union und den USA, der die Einhaltung europ&auml;ischer Datenschutzstandards bei Datenverarbeitungen in den USA gew&auml;hrleisten soll. Jedes nach dem DPF zertifizierte Unternehmen verpflichtet sich, diese Datenschutzstandards einzuhalten. Weitere Informationen hierzu erhalten Sie vom Anbieter unter folgendem Link: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n<h3>Wordfence<\/h3> <p>Wir haben Wordfence auf dieser Website eingebunden. Anbieter ist Defiant Inc., Defiant, Inc., 800 5th Ave Ste 4100, Seattle, WA 98104, USA (nachfolgend &bdquo;Wordfence&ldquo;).<\/p> <p>Wordfence dient dem Schutz unserer Website vor unerw&uuml;nschten Zugriffen oder b&ouml;sartigen Cyberattacken. Zu diesem Zweck stellt unsere Website eine dauerhafte Verbindung zu den Servern von Wordfence her, damit Wordfence seine Datenbanken mit den auf unserer Website get&auml;tigten Zugriffen abgleichen und ggf. blockieren kann.<\/p> <p>Die Verwendung von Wordfence erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an einem m&ouml;glichst effektiven Schutz seiner Website vor Cyberattacken. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie&szlig;lich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und &sect; 25 Abs. 1 TDDDG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger&auml;t des Nutzers (z.&nbsp;B. Device-Fingerprinting) im Sinne des TDDDG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p> <p>Die Daten&uuml;bertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest&uuml;tzt. Details finden Sie hier: <a href=\"https:\/\/www.wordfence.com\/help\/general-data-protection-regulation\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.wordfence.com\/help\/general-data-protection-regulation\/<\/a>.<\/p>\n\n<h4>Auftragsverarbeitung<\/h4> <p>Wir haben einen Vertrag &uuml;ber Auftragsverarbeitung (AVV) zur Nutzung des oben genannten Dienstes geschlossen. Hierbei handelt es sich um einen datenschutzrechtlich vorgeschriebenen Vertrag, der gew&auml;hrleistet, dass dieser die personenbezogenen Daten unserer Websitebesucher nur nach unseren Weisungen und unter Einhaltung der DSGVO verarbeitet.<\/p>\n<h2>8. eCommerce und Zahlungs&shy;anbieter<\/h2>\n<h3>Verarbeiten von Kunden- und Vertragsdaten<\/h3> <p>Wir erheben, verarbeiten und nutzen personenbezogene Kunden- und Vertragsdaten zur Begr&uuml;ndung, inhaltlichen Ausgestaltung und &Auml;nderung unserer Vertragsbeziehungen. Personenbezogene Daten &uuml;ber die Inanspruchnahme dieser Website (Nutzungsdaten) erheben, verarbeiten und nutzen wir nur, soweit dies erforderlich ist, um dem Nutzer die Inanspruchnahme des Dienstes zu erm&ouml;glichen oder abzurechnen. Rechtsgrundlage hierf&uuml;r ist Art. 6 Abs. 1 lit. b DSGVO.<\/p> <p>Die erhobenen Kundendaten werden nach Abschluss des Auftrags oder Beendigung der Gesch&auml;ftsbeziehung und Ablauf der ggf. bestehenden gesetzlichen Aufbewahrungsfristen gel&ouml;scht. Gesetzliche Aufbewahrungsfristen bleiben unber&uuml;hrt.<\/p>\n<h3>Daten&shy;&uuml;bermittlung bei Vertragsschluss f&uuml;r Online-Shops, H&auml;ndler und Warenversand<\/h3> <p>Wenn Sie Waren bei uns bestellen, geben wir Ihre personenbezogenen Daten an das zur Lieferung betraute Transportunternehmen sowie an den mit der Zahlungsabwicklung beauftragten Zahlungsdienstleister weiter. Es werden nur solche Daten herausgegeben, die der jeweilige Dienstleister zur Erf&uuml;llung seiner Aufgabe ben&ouml;tigt. Rechtsgrundlage hierf&uuml;r ist Art. 6 Abs. 1 lit. b DSGVO, der die Verarbeitung von Daten zur Erf&uuml;llung eines Vertrags oder vorvertraglicher Ma&szlig;nahmen gestattet. Sofern Sie eine entsprechende Einwilligung nach Art. 6 Abs. 1 lit. a DSGVO erteilt haben, werden wir Ihre E-Mail-Adresse an das mit der Lieferung betraute Transportunternehmen &uuml;bergeben, damit dieses Sie per E-Mail &uuml;ber den Versandstatus Ihrer Bestellung informieren kann; Sie k&ouml;nnen die Einwilligung jederzeit widerrufen.<\/p>\n<h3>Daten&shy;&uuml;bermittlung bei Vertragsschluss f&uuml;r Dienstleistungen und digitale Inhalte<\/h3> <p>Wir &uuml;bermitteln personenbezogene Daten an Dritte nur dann, wenn dies im Rahmen der Vertragsabwicklung notwendig ist, etwa an das mit der Zahlungsabwicklung beauftragte Kreditinstitut.<\/p> <p>Eine weitergehende &Uuml;bermittlung der Daten erfolgt nicht bzw. nur dann, wenn Sie der &Uuml;bermittlung ausdr&uuml;cklich zugestimmt haben. Eine Weitergabe Ihrer Daten an Dritte ohne ausdr&uuml;ckliche Einwilligung, etwa zu Zwecken der Werbung, erfolgt nicht.<\/p> <p>Grundlage f&uuml;r die Datenverarbeitung ist Art. 6 Abs. 1 lit. b DSGVO, der die Verarbeitung von Daten zur Erf&uuml;llung eines Vertrags oder vorvertraglicher Ma&szlig;nahmen gestattet.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0118b39 elementor-widget elementor-widget-erecht24\" data-id=\"0118b39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"erecht24.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"erecht24-elementor-widget\"><div style=\"word-wrap: break-word;\"><h3>Unsere Social-Media-Auftritte<\/h3> <h4>Diese Datenschutzerkl&auml;rung gilt f&uuml;r folgende Social-Media-Auftritte<\/h4> <ul>\n<li><a href=\"https:\/\/www.facebook.com\/profile.php?id=100064669334989#\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/profile.php?id=100064669334989#<\/a><\/li>\n<li><a href=\"https:\/\/www.instagram.com\/volksbildungswerk_klarenthal\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.instagram.com\/volksbildungswerk_klarenthal\/<\/a><\/li>\n<li><a href=\"https:\/\/youtube.com\/@volksbildungswerkklarentha8213\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/youtube.com\/@volksbildungswerkklarentha8213<\/a><\/li>\n<\/ul>\n <h4>Datenverarbeitung durch soziale Netzwerke<\/h4> <p>Wir unterhalten &ouml;ffentlich zug&auml;ngliche Profile in sozialen Netzwerken. Die im Einzelnen von uns genutzten sozialen Netzwerke finden Sie weiter unten.<\/p> <p>Soziale Netzwerke wie Facebook, X etc. k&ouml;nnen Ihr Nutzerverhalten in der Regel umfassend analysieren, wenn Sie deren Website oder eine Website mit integrierten Social-Media-Inhalten (z.&nbsp;B. Like-Buttons oder Werbebannern) besuchen. Durch den Besuch unserer Social-Media-Pr&auml;senzen werden zahlreiche datenschutzrelevante Verarbeitungsvorg&auml;nge ausgel&ouml;st. Im Einzelnen:<\/p> <p>Wenn Sie in Ihrem Social-Media-Account eingeloggt sind und unsere Social-Media-Pr&auml;senz besuchen, kann der Betreiber des Social-Media-Portals diesen Besuch Ihrem Benutzerkonto zuordnen. Ihre personenbezogenen Daten k&ouml;nnen unter Umst&auml;nden aber auch dann erfasst werden, wenn Sie nicht eingeloggt sind oder keinen Account beim jeweiligen Social-Media-Portal besitzen. Diese Datenerfassung erfolgt in diesem Fall beispielsweise &uuml;ber Cookies, die auf Ihrem Endger&auml;t gespeichert werden oder durch Erfassung Ihrer IP-Adresse.<\/p> <p>Mit Hilfe der so erfassten Daten k&ouml;nnen die Betreiber der Social-Media-Portale Nutzerprofile erstellen, in denen Ihre Pr&auml;ferenzen und Interessen hinterlegt sind. Auf diese Weise kann Ihnen interessenbezogene Werbung in- und au&szlig;erhalb der jeweiligen Social-Media-Pr&auml;senz angezeigt werden. Sofern Sie &uuml;ber einen Account beim jeweiligen sozialen Netzwerk verf&uuml;gen, kann die interessenbezogene Werbung auf allen Ger&auml;ten angezeigt werden, auf denen Sie eingeloggt sind oder eingeloggt waren.<\/p> <p>Bitte beachten Sie au&szlig;erdem, dass wir nicht alle Verarbeitungsprozesse auf den Social-Media-Portalen nachvollziehen k&ouml;nnen. Je nach Anbieter k&ouml;nnen daher ggf. weitere Verarbeitungsvorg&auml;nge von den Betreibern der Social-Media-Portale durchgef&uuml;hrt werden. Details hierzu entnehmen Sie den Nutzungsbedingungen und Datenschutzbestimmungen der jeweiligen Social-Media-Portale.<\/p> <h4>Rechtsgrundlage<\/h4> <p>Unsere Social-Media-Auftritte sollen eine m&ouml;glichst umfassende Pr&auml;senz im Internet gew&auml;hrleisten. Hierbei handelt es sich um ein berechtigtes Interesse im Sinne von Art. 6 Abs. 1 lit. f DSGVO. Die von den sozialen Netzwerken initiierten Analyseprozesse beruhen ggf. auf abweichenden Rechtsgrundlagen, die von den Betreibern der sozialen Netzwerke anzugeben sind (z.&nbsp;B. Einwilligung im Sinne des Art. 6 Abs. 1 lit. a DSGVO).<\/p> <h4>Verantwortlicher und Geltendmachung von Rechten<\/h4> <p>Wenn Sie einen unserer Social-Media-Auftritte (z.&nbsp;B. Facebook) besuchen, sind wir gemeinsam mit dem Betreiber der Social-Media-Plattform f&uuml;r die bei diesem Besuch ausgel&ouml;sten Datenverarbeitungsvorg&auml;nge verantwortlich. Sie k&ouml;nnen Ihre Rechte (Auskunft, Berichtigung, L&ouml;schung, Einschr&auml;nkung der Verarbeitung, Daten&uuml;bertragbarkeit und Beschwerde) grunds&auml;tzlich sowohl gg&uuml;. uns als auch gg&uuml;. dem Betreiber des jeweiligen Social-Media-Portals (z.&nbsp;B. gg&uuml;. Facebook) geltend machen.<\/p> <p>Bitte beachten Sie, dass wir trotz der gemeinsamen Verantwortlichkeit mit den Social-Media-Portal-Betreibern nicht vollumf&auml;nglich Einfluss auf die Datenverarbeitungsvorg&auml;nge der Social-Media-Portale haben. Unsere M&ouml;glichkeiten richten sich ma&szlig;geblich nach der Unternehmenspolitik des jeweiligen Anbieters.<\/p> <h4>Speicherdauer<\/h4> <p>Die unmittelbar von uns &uuml;ber die Social-Media-Pr&auml;senz erfassten Daten werden von unseren Systemen gel&ouml;scht, sobald Sie uns zur L&ouml;schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f&uuml;r die Datenspeicherung entf&auml;llt. Gespeicherte Cookies verbleiben auf Ihrem Endger&auml;t, bis Sie sie l&ouml;schen. Zwingende gesetzliche Bestimmungen &ndash; insb. Aufbewahrungsfristen &ndash; bleiben unber&uuml;hrt.<\/p> <p>Auf die Speicherdauer Ihrer Daten, die von den Betreibern der sozialen Netzwerke zu eigenen Zwecken gespeichert werden, haben wir keinen Einfluss. F&uuml;r Einzelheiten dazu informieren Sie sich bitte direkt bei den Betreibern der sozialen Netzwerke (z.&nbsp;B. in deren Datenschutzerkl&auml;rung, siehe unten).<\/p> <h4>Ihre Rechte<\/h4> <p>Sie haben jederzeit das Recht, unentgeltlich Auskunft &uuml;ber Herkunft, Empf&auml;nger und Zweck Ihrer gespeicherten personenbezogenen Daten zu erhalten. Ihnen steht au&szlig;erdem ein Recht auf Widerspruch, auf Daten&uuml;bertragbarkeit und ein Beschwerderecht bei der zust&auml;ndigen Aufsichtsbeh&ouml;rde zu. Ferner k&ouml;nnen Sie die Berichtigung, Sperrung, L&ouml;schung und unter bestimmten Umst&auml;nden die Einschr&auml;nkung der Verarbeitung Ihrer personenbezogenen Daten verlangen.<\/p> <h4>Soziale Netzwerke im Einzelnen<\/h4>\n<h5>Facebook<\/h5> <p>Wir verf&uuml;gen &uuml;ber ein Profil bei Facebook. Anbieter dieses Dienstes ist die Meta Platforms Ireland Limited, Merrion Road, Dublin 4, D04 X2K5, Irland (nachfolgend Meta). Die erfassten Daten werden nach Aussage von Meta auch in die USA und in andere Drittl&auml;nder &uuml;bertragen.<\/p> <p>Wir haben mit Meta eine Vereinbarung &uuml;ber gemeinsame Verarbeitung (Controller Addendum) geschlossen. In dieser Vereinbarung wird festgelegt, f&uuml;r welche Datenverarbeitungsvorg&auml;nge wir bzw. Meta verantwortlich ist, wenn Sie unsere Facebook-Page besuchen. Diese Vereinbarung k&ouml;nnen Sie unter folgendem Link einsehen: <a href=\"https:\/\/www.facebook.com\/legal\/terms\/page_controller_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/terms\/page_controller_addendum<\/a>.<\/p> <p><strong>Sie k&ouml;nnen Ihre Werbeeinstellungen selbstst&auml;ndig in Ihrem Nutzer-Account anpassen. Klicken Sie hierzu auf folgenden Link und loggen Sie sich ein:<\/strong> <a href=\"https:\/\/www.facebook.com\/settings?tab=ads\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/settings?tab=ads<\/a>.<\/p> <p>Die Daten&uuml;bertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest&uuml;tzt. Details finden Sie hier: <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a> und <a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/help\/566994660333381<\/a>.<\/p> <p>Details entnehmen Sie der Datenschutzerkl&auml;rung von Facebook: <a href=\"https:\/\/www.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/about\/privacy\/<\/a>.<\/p>\n<p>Das Unternehmen verf&uuml;gt &uuml;ber eine Zertifizierung nach dem &bdquo;EU-US Data Privacy Framework&ldquo; (DPF). Der DPF ist ein &Uuml;bereinkommen zwischen der Europ&auml;ischen Union und den USA, der die Einhaltung europ&auml;ischer Datenschutzstandards bei Datenverarbeitungen in den USA gew&auml;hrleisten soll. Jedes nach dem DPF zertifizierte Unternehmen verpflichtet sich, diese Datenschutzstandards einzuhalten. Weitere Informationen hierzu erhalten Sie vom Anbieter unter folgendem Link: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/4452\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/4452<\/a><\/p>\n<h5>Instagram<\/h5> <p>Wir verf&uuml;gen &uuml;ber ein Profil bei Instagram. Anbieter dieses Dienstes ist die Meta Platforms Ireland Limited, Merrion Road, Dublin 4, D04 X2K5, Irland.<\/p> <p>Die Daten&uuml;bertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest&uuml;tzt. Details finden Sie hier: <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a> und <a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/help\/566994660333381<\/a>.<\/p> <p>Details zu deren Umgang mit Ihren personenbezogenen Daten entnehmen Sie der Datenschutzerkl&auml;rung von Instagram: <a href=\"https:\/\/privacycenter.instagram.com\/policy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacycenter.instagram.com\/policy\/<\/a>.<\/p>\n<p>Das Unternehmen verf&uuml;gt &uuml;ber eine Zertifizierung nach dem &bdquo;EU-US Data Privacy Framework&ldquo; (DPF). Der DPF ist ein &Uuml;bereinkommen zwischen der Europ&auml;ischen Union und den USA, der die Einhaltung europ&auml;ischer Datenschutzstandards bei Datenverarbeitungen in den USA gew&auml;hrleisten soll. Jedes nach dem DPF zertifizierte Unternehmen verpflichtet sich, diese Datenschutzstandards einzuhalten. Weitere Informationen hierzu erhalten Sie vom Anbieter unter folgendem Link: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/4452\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/4452<\/a><\/p>\n<h5>YouTube<\/h5> <p>Wir verf&uuml;gen &uuml;ber ein Profil bei YouTube. Anbieter ist die Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland. Details zu deren Umgang mit Ihren personenbezogenen Daten entnehmen Sie der Datenschutzerkl&auml;rung von YouTube: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<p>Das Unternehmen verf&uuml;gt &uuml;ber eine Zertifizierung nach dem &bdquo;EU-US Data Privacy Framework&ldquo; (DPF). Der DPF ist ein &Uuml;bereinkommen zwischen der Europ&auml;ischen Union und den USA, der die Einhaltung europ&auml;ischer Datenschutzstandards bei Datenverarbeitungen in den USA gew&auml;hrleisten soll. Jedes nach dem DPF zertifizierte Unternehmen verpflichtet sich, diese Datenschutzstandards einzuhalten. Weitere Informationen hierzu erhalten Sie vom Anbieter unter folgendem Link: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a><\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e311058 elementor-widget elementor-widget-text-editor\" data-id=\"5e311058\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<h2 class=\"wp-block-heading\">PRIVACY POLICY VOLKSBILDUNGSWERK KLARENTHAL E.V.<\/h2>\n\n\n\n<p>As of: June 2018<\/p>\n\n\n\n<p><strong>We appreciate your interest in our website at www.klarenthal.org (hereinafter referred to as &#8222;Website&#8220;). Below, we provide detailed information about how we handle your data when you use our services. <\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Responsibility for Data Protection<\/h3>\n\n\n\n<p>The responsible entity for data protection is Volksbildungswerk Klarenthal e. V., legally represented by the board of Volksbildungswerk Klarenthal e. V.<br>Board: Monika Merkert, Burkard Mohr, Gert Pollok, Romanus Rumanus and Frauke Wetterich<\/p>\n\n\n\n<p>Contact: Geschwister-Scholl-Stra\u00dfe 10, 65197 Wiesbaden<br>info@klarenthal.org Tel.: 0611 72437920<br>(hereinafter referred to as &#8222;we&#8220;).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Storage of Access Data<\/h3>\n\n\n\n<p>Every time our website is accessed, access data is stored in a log file on our provider&#8217;s web server. This data set consists of<br>\u2013 the IP address of the requesting device<br>\u2013 date and time of access<br>\u2013 the name and URL of the requested file<br>\u2013 the amount of data transferred<br>\u2013 notification of whether the retrieval was successful<br>\u2013 identification data of the browser and operating system used<br>\u2013 website from which the access is made, and<br>\u2013 the name of your Internet access provider<br>The collection of this data is technically necessary. This data does not allow us to draw any conclusions about your person. Unfortunately, use of our website is not technically possible without providing your IP address.   <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Cookies<\/h3>\n\n\n\n<p><strong>3.1 Use to Ensure User-Friendliness<\/strong><\/p>\n\n\n\n<p>We store cookies on your device&#8217;s storage medium to make visiting our website attractive and to enable the use of certain functions. This serves our sales interest as a legitimate interest.<br>Cookies are small text files that are sent from the web server of our provider to your device&#8217;s browser and stored there. The cookies are needed to identify and authorize you for the entire duration of your visit after successful login to your user account. They are also needed when you provide information, e.g., when registering for a course without having registered, to save you from having to enter your data multiple times. These cookies are deleted from your device&#8217;s storage medium at the end of your browser session (so-called session cookies).    <br>Usually, your device&#8217;s browser is set to accept the creation and storage of cookies. You have the option to set your browser to reject the storage and use of cookies generally or for individual cases. However, in this case, the functionality of our website may be limited.  <\/p>\n\n\n\n<p><strong>3.2 YouTube<\/strong><\/p>\n\n\n\n<p>YouTube videos are embedded on some of our pages. For this, we use the domain www.youtube-nocookie.com, which does not set cookies and adheres better to good data protection practices (Method: Call up YouTube video, Share, Embed and set the bottom checkbox &#8222;Enable advanced privacy mode&#8220;). <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4. Social Plug-Ins<\/h3>\n\n\n\n<p>There are no plug-ins integrated on our website. There is only a link to our Facebook profile. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5. Course Registration<\/h3>\n\n\n\n<p>The data requested during registration for a course or trip is used to carry out pre-contractual measures and for contract fulfillment. A distinction is made between mandatory data (marked with an asterisk) and voluntarily provided data. Without the mandatory data (name, first name, address for sending the registration card, phone number, email for booking confirmation, date of birth, IBAN), no contract can be concluded. We collect your date of birth to ensure that you are of legal age, or to make any necessary arrangements if you are a minor. For special courses, e.g., children&#8217;s courses, providing the date of birth may be mandatory.<br>The request for your landline or mobile phone number is in our legitimate interest to be able to contact you directly in case of course changes. If you do not provide us with this data, we may not be able to reach you in time. The voluntary information is also used for contract execution. The email address is required to send the registration confirmation.<br>By providing IBAN, name, and first name of the account holder, you can grant us a direct debit mandate. The voluntary additional information also serves to execute the direct debit mandate. If you do not provide us with the mandatory bank details, no direct debit will be made and you must arrange payment of the course fee by other means.<br>All data provided by you is stored electronically. The resulting databases and applications may be managed by IT service providers commissioned by us. Failure to provide voluntary data has no consequences.           <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">6. User Account<\/h3>\n\n\n\n<p>You have the option to create a user account for our website. When creating a user account, you will be asked to provide your name, first name, and email address. The data fields marked with an asterisk are mandatory and serve to establish and execute the user agreement. The remaining information is voluntary.<br>Without providing your email address and setting up a password, we cannot authenticate your access data and offer a protected user account. Without providing your date of birth, we cannot verify whether we need your parents&#8216; consent to set up the user account. Failure to provide voluntary information has no consequences. Creating a user account is voluntary. You can register for courses at any time without a user account.<br>After creating a user account, you can view and edit your personal data, courses, wishlist, and bank details in it. You will also receive an overview of booked courses. Please make sure to log out of your user account before leaving our website. You can do this by clicking the &#8222;Logout&#8220; button in the user profile on our website. This serves to protect your data from unauthorized access by third parties.<br>You can cancel your user account at any time. We reserve the right to cancel your user account with a notice period of 4 weeks if you have not used the account for more than 3 years.            <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">7. Newsletter<\/h3>\n\n\n\n<p>You can grant us permission to use your email address to send advertising information about our offers. Without your consent, we will not use your email address for this purpose. You can revoke your consent at any time with effect for the future. You can inform us of the revocation through any communication channel (e.g., letter, email, link in the newsletter). By subscribing to our newsletter, you have made the following declaration: &#8222;I agree that Volksbildungswerk Klarenthal e. V. may inform me regularly about its courses via email. I can revoke this consent at any time with effect for the future.&#8220; When you open the newsletter or click on a link in it, this is logged via our web server (date, time, email address). This serves internal statistical purposes. This data is not combined to create personal usage profiles.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">8. Legal and Contractual Obligations to Provide Information<\/h3>\n\n\n\n<p>The provision of your data to us is neither contractually nor legally required.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">9. Storage Duration and Deletion of Data<\/h3>\n\n\n\n<p>We process and store your personal data only for the period necessary to achieve the storage purpose or as far as this is granted by the European legislator or other legislators in laws or regulations to which the controller is subject.<br>If the storage purpose is not applicable, or if a storage period prescribed by the European legislator or another competent legislator expires, the personal data are routinely blocked or erased in accordance with legal requirements. After the expiry of the period, the corresponding data is routinely deleted, as long as it is no longer necessary for the fulfillment or initiation of the contract.<br>Provided bank details are deleted after revocation of the direct debit authorization, successful payment of the course fee, or in the case of standing direct debit mandates, 48 months after the last use. Communication regarding legal claims is stored until the end of the limitation period.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">10. Sharing of Your Data<\/h3>\n\n\n\n<p>We only share your data with third parties if we are authorized or obliged to do so under applicable law. The same applies if we receive your data from third parties.<br>Authorization also exists if third parties process the data on our behalf. When we do not carry out our business activities ourselves (e.g., website operation, offer adjustment, participant support, creation and sending of advertising material, data analysis and possibly data cleansing, payment processing), but have them carried out by other contractors, and these activities are associated with the processing of your data, we have contractually obligated these companies in advance to use the data only for the purposes legally permitted to us. We are authorized to control these companies accordingly.<br>We pass on your name, email address, and (if provided) telephone number to the respective course instructor for the preparation and implementation of the course. This also includes contact in case of changes. Furthermore, for courses funded by state resources and those supported by the Employment Agency, a transfer to authorities may be necessary. These transfers are based on a legal obligation.<br>If you are in default with a payment, we reserve the right to forward your data (name, address, year of birth) to a collection service provider to enforce the claim as a legitimate interest.      <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">11. Data Security &amp; Data Protection<\/h3>\n\n\n\n<p>We take all necessary technical and organizational security measures to protect your personal data from loss and misuse. Your data is stored in a secure operating environment that is not accessible to the public.<br>As part of your registration for a course or trip, your personal data is transmitted in encrypted form.<br>For this purpose, we use SSL (Secure Socket Layer) encryption technology in particular.<br>Please note that complete confidentiality and data security cannot be guaranteed when communicating via email. We therefore recommend using postal mail for confidential information. Please consider that while we strive to create a secure and reliable website for users, third-party access cannot be completely ruled out.   <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">12. Your Rights (Information, Correction, Blocking, Deletion, Objection, Revocation, Transfer, Complaint)<\/h3>\n\n\n\n<p>You have the right to receive information free of charge at any time about what data about you is stored by us and for what purpose the storage takes place. Furthermore, you can object to data processing. You can also have your data transferred by us to someone else. In addition, you are entitled to have incorrect data corrected and data blocked or deleted, insofar as the storage is inadmissible or no longer necessary. You also have the right to revoke given consent with effect for the future. You can address your respective concern to us using the contact details mentioned in Section 1.<br>In addition to the aforementioned rights, you also have the fundamental right to lodge a complaint with a data protection supervisory authority.      <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">13. Contact Details for Data Protection<\/h3>\n\n\n\n<p>The contact details are: Geschwister-Scholl-Str. 10, 65197 Wiesbaden, verwaltung@klarenthal.org <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen &Uuml;berblick dar&uuml;ber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers&ouml;nlich identifiziert werden k&ouml;nnen. Ausf&uuml;hrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef&uuml;hrten Datenschutzerkl&auml;rung. Datenerfassung auf dieser Website [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"folder":[12],"class_list":["post-4870","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Policy - Volksbildungswerk Klarenthal e.V.<\/title>\n<meta name=\"description\" content=\"The protection of your privacy is important to us. Learn more about data protection and how we handle your personal data.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.klarenthal-vbw.de\/en\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - Volksbildungswerk Klarenthal e.V.\" \/>\n<meta property=\"og:description\" content=\"The protection of your privacy is important to us. Learn more about data protection and how we handle your personal data.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.klarenthal-vbw.de\/en\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Volksbildungswerk Klarenthal e.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-05T14:58:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"44\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/privacy-policy\\\/\",\"url\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/privacy-policy\\\/\",\"name\":\"Privacy Policy - Volksbildungswerk Klarenthal e.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/#website\"},\"datePublished\":\"2018-01-11T14:25:24+00:00\",\"dateModified\":\"2025-04-05T14:58:37+00:00\",\"description\":\"The protection of your privacy is important to us. Learn more about data protection and how we handle your personal data.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/privacy-policy\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/privacy-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/privacy-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/\",\"name\":\"Volksbildungswerk Klarenthal e.V.\",\"description\":\"Chancen. Bildung. Perspektiven\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/#organization\",\"name\":\"Volksbildungswerk Klarenthal e.V.\",\"url\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo.svg\",\"caption\":\"Volksbildungswerk Klarenthal e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy Policy - Volksbildungswerk Klarenthal e.V.","description":"The protection of your privacy is important to us. Learn more about data protection and how we handle your personal data.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.klarenthal-vbw.de\/en\/privacy-policy\/","og_locale":"en_US","og_type":"article","og_title":"Privacy Policy - Volksbildungswerk Klarenthal e.V.","og_description":"The protection of your privacy is important to us. Learn more about data protection and how we handle your personal data.","og_url":"https:\/\/www.klarenthal-vbw.de\/en\/privacy-policy\/","og_site_name":"Volksbildungswerk Klarenthal e.V.","article_modified_time":"2025-04-05T14:58:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"44\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.klarenthal-vbw.de\/en\/privacy-policy\/","url":"https:\/\/www.klarenthal-vbw.de\/en\/privacy-policy\/","name":"Privacy Policy - Volksbildungswerk Klarenthal e.V.","isPartOf":{"@id":"https:\/\/www.klarenthal-vbw.de\/en\/#website"},"datePublished":"2018-01-11T14:25:24+00:00","dateModified":"2025-04-05T14:58:37+00:00","description":"The protection of your privacy is important to us. Learn more about data protection and how we handle your personal data.","breadcrumb":{"@id":"https:\/\/www.klarenthal-vbw.de\/en\/privacy-policy\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.klarenthal-vbw.de\/en\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.klarenthal-vbw.de\/en\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.klarenthal-vbw.de\/en\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/www.klarenthal-vbw.de\/en\/#website","url":"https:\/\/www.klarenthal-vbw.de\/en\/","name":"Volksbildungswerk Klarenthal e.V.","description":"Chancen. Bildung. Perspektiven","publisher":{"@id":"https:\/\/www.klarenthal-vbw.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.klarenthal-vbw.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.klarenthal-vbw.de\/en\/#organization","name":"Volksbildungswerk Klarenthal e.V.","url":"https:\/\/www.klarenthal-vbw.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.klarenthal-vbw.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.klarenthal-vbw.de\/wp-content\/uploads\/2025\/02\/logo.svg","contentUrl":"https:\/\/www.klarenthal-vbw.de\/wp-content\/uploads\/2025\/02\/logo.svg","caption":"Volksbildungswerk Klarenthal e.V."},"image":{"@id":"https:\/\/www.klarenthal-vbw.de\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.klarenthal-vbw.de\/en\/wp-json\/wp\/v2\/pages\/4870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.klarenthal-vbw.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.klarenthal-vbw.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.klarenthal-vbw.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.klarenthal-vbw.de\/en\/wp-json\/wp\/v2\/comments?post=4870"}],"version-history":[{"count":0,"href":"https:\/\/www.klarenthal-vbw.de\/en\/wp-json\/wp\/v2\/pages\/4870\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.klarenthal-vbw.de\/en\/wp-json\/wp\/v2\/media?parent=4870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.klarenthal-vbw.de\/en\/wp-json\/wp\/v2\/categories?post=4870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.klarenthal-vbw.de\/en\/wp-json\/wp\/v2\/tags?post=4870"},{"taxonomy":"folder","embeddable":true,"href":"https:\/\/www.klarenthal-vbw.de\/en\/wp-json\/wp\/v2\/folder?post=4870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}