{"id":7942,"date":"2025-07-23T01:37:18","date_gmt":"2025-07-22T23:37:18","guid":{"rendered":"https:\/\/vbw.entwicklung-mediengewerk.de\/?post_type=termin&#038;p=7942"},"modified":"2025-07-23T01:37:18","modified_gmt":"2025-07-22T23:37:18","slug":"mittwoch-geschaeftsstelle-betz","status":"publish","type":"termin","link":"https:\/\/www.klarenthal-vbw.de\/en\/termin\/mittwoch-geschaeftsstelle-betz\/","title":{"rendered":"Mittwoch"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":true},"categories":[],"tags":[78],"ort":[158],"teamtag":[123],"class_list":["post-7942","termin","type-termin","status-publish","hentry","tag-stadtteilarbeit","ort-geschwister-scholl-strasse-10","teamtag-sabine-betz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mittwoch - Volksbildungswerk Klarenthal e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.klarenthal-vbw.de\/en\/termin\/mittwoch-geschaeftsstelle-betz\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mittwoch - Volksbildungswerk Klarenthal e.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.klarenthal-vbw.de\/en\/termin\/mittwoch-geschaeftsstelle-betz\/\" \/>\n<meta property=\"og:site_name\" content=\"Volksbildungswerk Klarenthal e.V.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/termin\\\/mittwoch-geschaeftsstelle-betz\\\/\",\"url\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/termin\\\/mittwoch-geschaeftsstelle-betz\\\/\",\"name\":\"Mittwoch - Volksbildungswerk Klarenthal e.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/#website\"},\"datePublished\":\"2025-07-22T23:37:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/termin\\\/mittwoch-geschaeftsstelle-betz\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/termin\\\/mittwoch-geschaeftsstelle-betz\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/termin\\\/mittwoch-geschaeftsstelle-betz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mittwoch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/\",\"name\":\"Volksbildungswerk Klarenthal e.V.\",\"description\":\"Chancen. Bildung. Perspektiven\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/#organization\",\"name\":\"Volksbildungswerk Klarenthal e.V.\",\"url\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo.svg\",\"caption\":\"Volksbildungswerk Klarenthal e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.klarenthal-vbw.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mittwoch - Volksbildungswerk Klarenthal e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.klarenthal-vbw.de\/en\/termin\/mittwoch-geschaeftsstelle-betz\/","og_locale":"en_US","og_type":"article","og_title":"Mittwoch - Volksbildungswerk Klarenthal e.V.","og_url":"https:\/\/www.klarenthal-vbw.de\/en\/termin\/mittwoch-geschaeftsstelle-betz\/","og_site_name":"Volksbildungswerk Klarenthal e.V.","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.klarenthal-vbw.de\/en\/termin\/mittwoch-geschaeftsstelle-betz\/","url":"https:\/\/www.klarenthal-vbw.de\/en\/termin\/mittwoch-geschaeftsstelle-betz\/","name":"Mittwoch - Volksbildungswerk Klarenthal e.V.","isPartOf":{"@id":"https:\/\/www.klarenthal-vbw.de\/en\/#website"},"datePublished":"2025-07-22T23:37:18+00:00","breadcrumb":{"@id":"https:\/\/www.klarenthal-vbw.de\/en\/termin\/mittwoch-geschaeftsstelle-betz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.klarenthal-vbw.de\/en\/termin\/mittwoch-geschaeftsstelle-betz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.klarenthal-vbw.de\/en\/termin\/mittwoch-geschaeftsstelle-betz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.klarenthal-vbw.de\/en\/"},{"@type":"ListItem","position":2,"name":"Mittwoch"}]},{"@type":"WebSite","@id":"https:\/\/www.klarenthal-vbw.de\/en\/#website","url":"https:\/\/www.klarenthal-vbw.de\/en\/","name":"Volksbildungswerk Klarenthal e.V.","description":"Chancen. Bildung. Perspektiven","publisher":{"@id":"https:\/\/www.klarenthal-vbw.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.klarenthal-vbw.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.klarenthal-vbw.de\/en\/#organization","name":"Volksbildungswerk Klarenthal e.V.","url":"https:\/\/www.klarenthal-vbw.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.klarenthal-vbw.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.klarenthal-vbw.de\/wp-content\/uploads\/2025\/02\/logo.svg","contentUrl":"https:\/\/www.klarenthal-vbw.de\/wp-content\/uploads\/2025\/02\/logo.svg","caption":"Volksbildungswerk Klarenthal e.V."},"image":{"@id":"https:\/\/www.klarenthal-vbw.de\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.klarenthal-vbw.de\/en\/wp-json\/wp\/v2\/termin\/7942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.klarenthal-vbw.de\/en\/wp-json\/wp\/v2\/termin"}],"about":[{"href":"https:\/\/www.klarenthal-vbw.de\/en\/wp-json\/wp\/v2\/types\/termin"}],"wp:attachment":[{"href":"https:\/\/www.klarenthal-vbw.de\/en\/wp-json\/wp\/v2\/media?parent=7942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.klarenthal-vbw.de\/en\/wp-json\/wp\/v2\/categories?post=7942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.klarenthal-vbw.de\/en\/wp-json\/wp\/v2\/tags?post=7942"},{"taxonomy":"ort","embeddable":true,"href":"https:\/\/www.klarenthal-vbw.de\/en\/wp-json\/wp\/v2\/ort?post=7942"},{"taxonomy":"teamtag","embeddable":true,"href":"https:\/\/www.klarenthal-vbw.de\/en\/wp-json\/wp\/v2\/teamtag?post=7942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}